{"id":1264,"date":"2022-12-08T18:11:02","date_gmt":"2022-12-08T17:11:02","guid":{"rendered":"https:\/\/bike-taxi.it\/privacy\/"},"modified":"2023-06-14T20:31:52","modified_gmt":"2023-06-14T18:31:52","slug":"privacy","status":"publish","type":"page","link":"https:\/\/fahrradtransport.it\/it\/privacy\/","title":{"rendered":"Privacy"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|off&#8221; admin_label=&#8221;MainMenu&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; custom_padding=&#8221;2vh||29px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; parallax=&#8221;on&#8221; width=&#8221;82%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-6px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_menu db_title_and_tagline_valign=&#8221;bottom&#8221; active_link_color=&#8221;rgba(255,255,255,0.55)&#8221; dropdown_menu_bg_color=&#8221;#7a7a7a&#8221; dropdown_menu_line_color=&#8221;#FFFFFF&#8221; logo=&#8221;https:\/\/fahrradtransport.it\/wp-content\/uploads\/2023\/04\/CronDriveBikeTransportWhiteTransp3.png&#8221; logo_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiaG9tZV91cmwiLCJzZXR0aW5ncyI6e319@&#8221; logo_max_width=&#8221;35%&#8221; show_search_icon=&#8221;on&#8221; search_icon_color=&#8221;#FFFFFF&#8221; menu_icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.20.2&#8243; _dynamic_attributes=&#8221;logo_url&#8221; _module_preset=&#8221;default&#8221; menu_font=&#8221;|600|||||||&#8221; menu_text_color=&#8221;#FFFFFF&#8221; menu_font_size=&#8221;22px&#8221; menu_line_height=&#8221;1.1em&#8221; db_tagline_text_align=&#8221;left&#8221; db_tagline_text_color=&#8221;#FFFFFF&#8221; db_tagline_font_size=&#8221;20px&#8221; db_tagline_line_height=&#8221;1.6em&#8221; background_enable_color=&#8221;off&#8221; background_layout=&#8221;dark&#8221; custom_padding=&#8221;8px|2px|11px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_menu][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;HeaderBild&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(252,164,50,0.09) 0%|rgba(183,30,0,0.14) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/fahrradtransport.it\/wp-content\/uploads\/2022\/12\/HeaderVanGrMidQua.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; custom_padding=&#8221;12vh||11vh||false|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row padding_top_bottom_link_2=&#8221;true&#8221; padding_left_right_link_2=&#8221;true&#8221; _builder_version=&#8221;4.19.2&#8243; background_color=&#8221;rgba(255,255,255,0.91)&#8221; custom_padding=&#8221;|30px||30px|false|true&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.19.2&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;33px&#8221; header_line_height=&#8221;1.4em&#8221; header_2_text_align=&#8221;center&#8221; header_4_font=&#8221;|700||on|||||&#8221; header_4_text_align=&#8221;center&#8221; header_4_text_color=&#8221;rgba(0,0,0,0.5)&#8221; header_4_font_size=&#8221;14px&#8221; header_4_letter_spacing=&#8221;1px&#8221; header_4_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||6px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<h1>Privacy &#8211; Cookies <strong>Informativa sulla protezione della privacy<\/strong><\/h1>\n<h2>Responsabile ai sensi del regolamento sulla protezione dei dati personali<\/h2>\n<h4><\/h4>\n<p>[\/et_pb_text][et_pb_blurb title=&#8221;Roland Niederkofler &#8211; Cron Drive&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xf1ea;||fa||400&#8243; icon_color=&#8221;#293600&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;20px&#8221; _builder_version=&#8221;4.19.2&#8243; header_font=&#8221;Raleway|700|||||||&#8221; header_text_color=&#8221;#1d2600&#8243; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;20px||5px|||&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;+39 366 10 33 444&#8243; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe090;||divi||400&#8243; icon_color=&#8221;#293600&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;20px&#8221; _builder_version=&#8221;4.19.2&#8243; header_font=&#8221;Raleway|700||on|||||&#8221; header_text_color=&#8221;#1d2600&#8243; header_font_size=&#8221;19px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font_size=&#8221;18px&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;3px||14px|||&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;info@crondrive.it&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe076;||divi||400&#8243; icon_color=&#8221;#293600&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;20px&#8221; _builder_version=&#8221;4.19.2&#8243; header_font=&#8221;Raleway|700|||||||&#8221; header_text_color=&#8221;#1d2600&#8243; header_font_size=&#8221;18px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;20px||13px|||&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Bruneck | Brunico  S\u00fcdtirol | South Tyrol | Alto Adige&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;&#xe081;||divi||400&#8243; icon_color=&#8221;#293600&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;20px&#8221; _builder_version=&#8221;4.19.2&#8243; header_font=&#8221;Raleway|700|||||||&#8221; header_text_color=&#8221;#1d2600&#8243; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;20px|||&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;MWSTR. | PART.IVA |  VAT: IT03168740219&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;20px&#8221; _builder_version=&#8221;4.19.2&#8243; header_font=&#8221;Raleway|700|||||||&#8221; header_text_color=&#8221;#1d2600&#8243; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;20px|||&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_blurb][et_pb_text _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;]<\/p>\n<p>Nello specifico, Le forniamo le seguenti informazioni:<\/p>\n<p>L\u00b4 impresa CronDrive Brunico utilizzer\u00e0 i Vostri dati per i seguenti scopi:<\/p>\n<p>\u203a invio di email e comunicazioni;<\/p>\n<p>\u203a comunicazioni con Lei;<\/p>\n<p>\u203a comunicazioni e operazioni IT;<\/p>\n<p>\u203a gestione finanziaria;<\/p>\n<p>\u203a fornire a Lei materiale promozionale a Sua richiesta;<\/p>\n<p>\u203a procedimenti legali: creazione, esercizio e difesa di diritti;<\/p>\n<p>\u203a adeguamento alla legge applicabile;<\/p>\n<p>\u203a miglioramento del sito;<\/p>\n<p>\u203a adempiere a eventuali obblighi contrattuali nei confronti dell\u2019interessato, alla tutela del credito e gestione del debito.<\/p>\n<p>\u203a registrazione del Suo account;<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 garantisce ai sensi della Normativa Privacy Applicabile che il trattamento dei dati personali avviene nel rispetto dei diritti fondamentali nonch\u00e9 della dignit\u00e0 dell\u2019interessato, in particolare per quanto riguarda la segretezza, l\u2019identit\u00e0 personale, il diritto alla tutela degli stessi, nonch\u00e9 alla loro cancellazione su richiesta dell\u2019interessato.<\/p>\n<p>In relazione alle finalit\u00e0 di cui sopra, i Vostri dati personali saranno comunicati se necessario:<\/p>\n<p>\u203a alle Pubbliche Amministrazioni e Autorit\u00e0, ove previsto dalla legge e dalla Normativa Privacy Applicabile;<\/p>\n<p>\u203a a Istituti di credito con i quali la nostra societ\u00e0 ha rapporti per la gestione dei crediti\/debiti e l\u2019intermediazione finanziaria;<\/p>\n<p>\u203a a tutte quelle persone fisiche e\/o giuridiche, pubbliche e\/o private (quali, titolo indicativo e non esaustivo, studi di consulenza legale, amministrativa e fiscale, uffici giudiziari, Camere di Commercio), quando la comunicazione risulti necessaria o funzionale allo svolgimento della nostra attivit\u00e0 e nei modi e per le finalit\u00e0 sopra elencate.<\/p>\n<p>I dati personali trattati dalla nostra impresa non sono soggetti a diffusione. Il trattamento potr\u00e0 effettuarsi con o senza l\u2019ausilio di mezzi elettronici e comunque automatizzati e comprender\u00e0 tutte le operazioni previste all\u2019art. 4 comma 1, 2), Reg. 679\/2016 e necessarie al trattamento in questione. Comunque, il trattamento sar\u00e0 effettuato nell\u2019osservanza di ogni misura cautelativa, che ne garantisca la sicurezza e la riservatezza.<\/p>\n<p>In ogni momento potrete esercitare i vostri diritti nei confronti del titolare del trattamento, ai sensi del Capo III del Reg. 679\/2016.<\/p>\n<p>In proposito, Le ricordiamo che i vostri diritti includono:<\/p>\n<p>\u203a il diritto di non fornire a noi i Suoi Dati Personali (comunque, La preghiamo di notare che in tal caso noi potremmo non essere in grado di fornire a Lei i vantaggi del Sito);<\/p>\n<p>\u203a il diritto di richiedere l\u2019accesso ai, o copia dei, Suoi dati personali, unitamente alle informazioni connesse alla natura, al trattamento, alla divulgazione di detti dati personali;<\/p>\n<p>\u203a il diritto di richiedere rettifiche di qualsivoglia inesattezza nei Suoi dati personali;<\/p>\n<p>\u203a il diritto di richiedere, su basi legittime:<\/p>\n<p>la cancellazione dei Suoi Dati Personali;<\/p>\n<p>la limitazione del trattamento dei Suoi dati personali;<\/p>\n<p>\u203a il diritto di contestare, su basi legittime, il trattamento da parte nostra o per nostro conto dei suoi dati Personali;<\/p>\n<p>\u203a il diritto di ottenere il trasferimento di Dati Personali verso altri Titolari, in un formato strutturato, usato nella prassi e leggibile digitalmente, entro i fini applicabili;<\/p>\n<p>\u203a allorch\u00e9 noi Trattiamo i Suoi Dati Personali sulla base del Suo consenso, il diritto di ritirare il Suo consenso (posto che tale ritiro non inficia qualsivoglia Trattamento legittimamente effettuato prima della data in cui noi riceviamo notizia del ritiro stesso n\u00e9 evita il trattamento di Suoi Dati Personali fatto facendo affidamento su ogni altra base legale); e<\/p>\n<p>\u203a il diritto di presentare doglianze innanzi ad una Autorit\u00e0 Garante per la protezione dei dati personali in relazione al trattamento da parte nostra o per nostro conto dei Suoi dati personali.<\/p>\n<p>Quanto sopra non pregiudica i Suoi diritti inderogabili. I diritti in oggetto possono essere esercitati, anche per il tramite di un incaricato, mediante richiesta rivolta al Titolare:<\/p>\n<p>L\u00b4 impresa CronDrive Brunico<\/p>\n<h4>Tel. +39 366 10 33 444<\/h4>\n<p>email: info@crondrive.it<\/p>\n<p>www.crondrive.it<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>Il titolare del trattamento in oggetto \u00e8:<\/p>\n<p>L\u00b4 impresa CronDrive Brunico, nella persona del rappresentante legale, con sede in 39031 Brunico (BZ), \u00a0<\/p>\n<p>Tel. +39 366 10 33 444<\/p>\n<p>email: info@crondrive.it<\/p>\n<p>&nbsp;<\/p>\n<p>www.crondrive.it<\/p>\n<p>Responsabile per il contenuto:<\/p>\n<p>L\u00b4 impresa CronDrive Brunico, nella persona del rappresentante legale con sede in 39031 Brunico (BZ), \u00a0<\/p>\n<p>Tel. +39 366 10 33 444<\/p>\n<p>email: info@crondrive.it<\/p>\n<p>&nbsp;<\/p>\n<p>www.crondrive.it<\/p>\n<p>&nbsp;<\/p>\n<p>Informativa sui cookie<\/p>\n<p>Che cosa sono i cookie:<\/p>\n<p>Il cookie \u00e8 un piccolo file di testo contenente una certa quantit\u00e0 di informazioni scambiato tra un sito internet ed il tuo terminale (solitamente il browser). Quando si visita di nuovo lo stesso sito o qualunque altro sito il dispositivo dell&#8217;utente verifica la presenza di un cookie riconosciuto, in modo da potere leggere le informazioni in esso contenute. I diversi cookie contengono informazioni diverse e sono utilizzati per scopi differenti (navigazione efficiente nelle pagine di un medesimo sito, profilazione al fine di inviare messaggi mirati, analisi sul numero delle visite al sito). I cookie servono ad evitare di dover inserire determinate informazioni ogniqualvolta visitate lo stesso sito.<\/p>\n<p>Nel corso della navigazione l&#8217;utente pu\u00f2 ricevere sul suo terminale anche cookie inviati da siti o da web server diversi (c.d. terze parti).<\/p>\n<p>Pi\u00f9 in generale, alcuni cookie (definiti cookie di sessione) sono assegnati al dispositivo dell&#8217;utente soltanto per la durata dell&#8217;accesso al sito e scadono automaticamente alla chiusura del browser. Altri cookie (definiti persistenti) restano nel dispositivo per un periodo di tempo prolungato.<\/p>\n<p>Le specifiche finalit\u00e0 delle diverse tipologie di cookie installati in questo sito sono di seguito descritte.<\/p>\n<p>Cookie tecnici:<\/p>\n<p>Si tratta di cookie utilizzati specificamente per permettere il corretto funzionamento e la fruizione dei nostri siti. I cookie tecnici vengono ad esempio utilizzati per la funzionalit\u00e0 di login dell&#8217;utente. Sono erogati principalmente dai server di CronDrive o, nel caso dell&#8217;integrazione di servizi esterni come i social network, da terze parti.<\/p>\n<p>Cookie di profilazione:<\/p>\n<p>Si tratta di cookie utilizzati al fine di inviare attraverso la rete Google Advertising o altre imprese pubblicitarie messaggi pubblicitari in linea con le preferenze manifestate dall&#8217;utente nell&#8217;ambito della navigazione in rete. Possono essere erogati da nostri server oppure tramite il nostro sito da terze parti. Le aziende che offrono o pubblicizzano i propri prodotti tramite questo sito potrebbero assegnare cookie ai terminali degli utenti.<\/p>\n<p>Cookie analitici:<\/p>\n<p>Si tratta di cookie utilizzati per analisi statistiche sull\u2019utilizzo di CronDrive Questo tipo di cookie raccoglie informazioni in forma anonima sull&#8217;attivit\u00e0 degli utenti nel sito. Questo tipo di cookie viene erogato esclusivamente da terze parti.<\/p>\n<p>Come prestare o revocare il consenso:<\/p>\n<p>Il consenso all&#8217;utilizzo dei cookie viene prestato inizialmente cliccando sul tasto &#8220;ok&#8221; posizionato all&#8217;interno dell&#8217;informativa breve \/ banner iniziale e pu\u00f2 essere revocato in ogni momento.<\/p>\n<p>L&#8217;erogazione di tutti i cookie, sia di prime che di terze parti, \u00e8 disattivabile intervenendo sulle impostazioni del browser in uso; \u00e8 bene notare per\u00f2 che questo potrebbe rendere inutilizzabili i siti qualora si bloccassero i cookie indispensabili per l&#8217;erogazione delle funzionalit\u00e0.<\/p>\n<p>Siti di terze parti:<\/p>\n<p>I siti di terze parti a cui \u00e8 possibile accedere tramite questo sito web non sono coperti dalla presente informativa. CronDrive declina ogni responsabilit\u00e0 in merito ad essi. Le categorie di cookie utilizzate e il tipo di trattamento di dati personali da parte di queste aziende sono regolati in conformit\u00e0 all&#8217;informativa rese da queste aziende.<\/p>\n<p>Le terze parti che principalmente operano tramite CronDrive, come tramite ogni altro sito, son GooglePlus\/GoogleAnalytics, Facebook, Twitter e Addthis.<\/p>\n<p>Per ulteriori informazioni e per come disattivare i cookie, anche di terze parti vai sul sito: www.youronlinechoices.eu\/it<\/p>\n<p>Istruzioni per disattivare I cookie:<\/p>\n<p>Google Chrome: https:\/\/support.google.com\/chrome\/answer\/95647?hl=it<\/p>\n<p>Internet Explorer: https:\/\/support.microsoft.com\/it-it\/help\/17442\/windows-internet-explorer-delete-manage-cookies<\/p>\n<p>Mozilla Firefox: https:\/\/support.mozilla.org\/it\/kb\/Attivare%20e%20disattivare%20i%20cookie<\/p>\n<p>Safari: https:\/\/support.apple.com\/it-it\/HT201265<\/p>\n<p>&nbsp;<\/p>\n<p>Privacy disclaimer dei seguenti siti:<\/p>\n<p>Facebook: https:\/\/www.facebook.com\/policies\/cookies\/<\/p>\n<p>Twitter: https:\/\/twitter.com\/privacy?lang=it<\/p>\n<p>Google, Youtube: https:\/\/policies.google.com\/technologies\/cookies<\/p>\n<p>LinkedIn: https:\/\/www.linkedin.com\/legal\/privacy-policy?_l=it_it<\/p>\n<p>Instagram: https:\/\/help.instagram.com\/155833707900388<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>DATA PROTECTION POLICY<\/p>\n<p>La presente Data Protection Policy \u00e8 resa da<\/p>\n<p>L\u00b4 impresa CronDrive Brunico<\/p>\n<p>con sede in 39031 Brunico (BZ), \u00a0<\/p>\n<p>Tel. +39 366 10 33 444<\/p>\n<p>email: info@crondrive.it<\/p>\n<p>&nbsp;<\/p>\n<p>www.crondrive.it<\/p>\n<p>(di seguito denominata, anche, \u201cCRONDRIVE\u201d) ai sensi degli artt. 4 e ss. del Regolamento generale sulla protezione dei dati n. 2016\/679\/UE (&#8220;Regolamento&#8221;). In virt\u00f9 della presente Data Protection Policy, CRONDRIVE\u00a0 \u00e8 Titolare del trattamento.<\/p>\n<p>Introduzione<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 si impegna nella protezione della privacy di ciascun soggetto interessato. Lo scopo della presente Data Protection Policy \u00e8 di informare sui tipi di dati e informazioni che CRONDRIVE\u00a0 raccoglie sugli utenti, come utilizzare tali informazioni e come vengono rese note a terze parti.<\/p>\n<p>La presente Data Protection Policy non si applica alle informazioni che vengono fornite direttamente a, o che sono raccolte da terze parti, le quali sono controllate da dette terze parti e il cui utilizzo potrebbe essere disciplinato da differenti privacy policy e\/o termini di utilizzo. In quest\u2019ultimo caso, \u00e8 onere dell\u2019utente visionare le privacy policy e\/o i termini di utilizzo applicabili.<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 non richiede all\u2019Interessato di fornire dati c.d. \u201cparticolari\u201d, ovvero, secondo quanto previsto dal GDPR (art. 9), i dati personali che rivelino l&#8217;origine razziale o etnica, le opinioni politiche, le convinzioni religiose o filosofiche, o l&#8217;appartenenza sindacale, nonch\u00e9 dati genetici, dati biometrici intesi a identificare in modo univoco una persona fisica, dati relativi alla salute o alla vita sessuale o all&#8217;orientamento sessuale della persona. Nel caso in cui la prestazione richiesta ad CRONDRIVE\u00a0 imponesse il trattamento di tali dati, l\u2019Interessato ricever\u00e0 preventivamente apposita informativa e sar\u00e0 ad Egli richiesto di prestare apposito consenso.<\/p>\n<p>DEFINIZIONI IMPORTANTI<\/p>\n<p>\u201cGiurisdizione Adeguata\u201d una giurisdizione che \u00e8 stata formalmente indicata dalla Commissione Europea quale giurisdizione dotata di un adeguato livello di protezione dei Dati Personali.<\/p>\n<p>\u201cTitolare\u201d indica il soggetto che decide come e perch\u00e9 Trattare Dati Personali.<\/p>\n<p>\u201cAutorit\u00e0 Garante per la Protezione dei Dati Personali\u201d indica una autorit\u00e0 pubblica indipendente formalmente incaricata di supervisionare e garantire il rispetto della vigente e applicabile disciplina in materia di protezione dei dati personali.<\/p>\n<p>\u201cSEE\u201d indica lo Spazio Economico Europeo.<\/p>\n<p>\u201cMateriali\u201d indica congiuntamente ogni e ciascun Contenuto, Contenuto Sottoscritto (ove applicabile e quale meglio definito nel proseguo), messaggistica, blogging, chatting, social networking, informazione, pubblicit\u00e0 e\/o link internet, ecc., accessibile o consegnato attraverso il Sito.<\/p>\n<p>\u201cDati Personali\u201d indica le informazioni riguardanti una persona fisica o le informazioni dalle quali una persona fisica \u00e8 direttamente o indirettamente identificata o identificabile, in particolare mediante riferimento a un elemento di individuazione quale un nome, un numero identificativo, localizzazioni geografiche, identificatori online ovvero mediante riferimento a uno o pi\u00f9 elementi fisici, psicologici, genetici, mentali, economici, culturali o sociali che identificano una determinata persona fisica.<\/p>\n<p>\u201cTrattamento\u201d indica qualunque operazione effettuata sui Dati Personali anche senza l\u2019ausilio di strumenti elettronici, quali la raccolta, la registrazione, l\u2019organizzazione, la conservazione, l\u2019elaborazione, la modificazione, il recupero, la consultazione, l\u2019utilizzo, la comunicazione, la diffusione, ovvero la messa a disposizione in altro modo, l\u2019interconnessione, la riduzione, la cancellazione e la distruzione di dati personali.<\/p>\n<p>\u201cDati Sensibili\u201d indica qualunque dato personale riferito a razza o etnia, opinioni politiche, convinzioni religiose o filosofiche, adesioni a partiti o sindacati, salute fisica e mentale, abitudini sessuali, informazioni giudiziarie relative a procedimenti penali giudicati o pendenti, numero di identificazione nazionale o qualsiasi altra informazione suscettibile di essere considerata sensibile ai sensi del Regolamento e di tutte le altre leggi e regolamenti applicabili in materia di protezione dei dati personali.<\/p>\n<p>\u201cSito\u201d indica ogni e ciascun sito web gestito o mantenuto da CRONDRIVE\u00a0 o per conto di CRONDRIVE<\/p>\n<p>\u201cApplicazione(i)\u201d indica una applicazione software integrabile, scaricabile e\/o eseguibile di titolarit\u00e0 CRONDRIVE\u00a0 o di terze parti e resa disponibile sul Sito(i).<\/p>\n<p>\u201cContenuto\u201d indica ogni elemento audio o video nonch\u00e9 ogni idea offerta da CRONDRIVE\u00a0 o terze parti, inclusi a titolo esemplificativo e non esaustivo dati, film, video, fotografie, software, giochi, elementi grafici e design, ritratti e immagini, opere artistiche, musica, suoni informazioni e altri materiali, tangibili e intangibili, incluse opere derivate, su ogni e ciascun media e formato, esistente o futuro.<\/p>\n<p>L\u2019iscrizione anagrafica e le richieste di contatto e\/o di materiale informativo<\/p>\n<p>Il trattamento dei dati personali dell\u2019Interessato avviene per dar corso alle attivit\u00e0 preliminari e conseguenti alla richiesta di iscrizione anagrafica, alla gestione delle richieste di informazioni e di contatto e\/o di invio di materiale informativo, nonch\u00e9 per l\u2019adempimento di ogni altro obbligo derivante.<\/p>\n<p>Base giuridica di tali trattamenti \u00e8 l\u2019adempimento delle prestazioni inerenti alla richiesta di iscrizione, di informazioni e di contatto e\/o di invio di materiale informativo ed il rispetto di obblighi di legge.<\/p>\n<p>La gestione del rapporto contrattuale<\/p>\n<p>Il trattamento dei dati personali dell\u2019Interessato avviene per dar corso alle attivit\u00e0 preliminari e conseguenti all\u2019acquisto di un Servizio e\/o di un Prodotto, la gestione del relativo ordine, l\u2019erogazione del Servizio stesso e\/o la produzione e\/o la spedizione del Prodotto acquistato, la relativa fatturazione e la gestione del pagamento, la trattazione dei reclami e\/o delle segnalazioni al servizio di assistenza e l\u2019erogazione dell\u2019assistenza stessa, la prevenzione delle frodi nonch\u00e9 l\u2019adempimento di ogni altro obbligo derivante dal contratto.<\/p>\n<p>Base giuridica di tali trattamenti \u00e8 l\u2019adempimento delle prestazioni inerenti al rapporto contrattuale ed il rispetto di obblighi di legge.<\/p>\n<p>Le attivit\u00e0 promozionali su Servizi\/Prodotti analoghi a quelli acquistati dall\u2019Interessato (Considerando 47 GDPR)<\/p>\n<p>Il titolare del trattamento, anche senza un tuo esplicito consenso, potr\u00e0 utilizzare i dati di contatto comunicati dall\u2019Interessato, ai fini di vendita diretta di propri Servizi\/Prodotti, limitatamente al caso in cui si tratti di Servizi\/Prodotti analoghi a quelli oggetto della vendita, a meno che l\u2019Interessato non si opponga esplicitamente.<\/p>\n<p>Le attivit\u00e0 di promozione commerciale su Servizi\/Prodotti differenti rispetto a quelli acquistati dall\u2019Interessato<\/p>\n<p>I dati personali dell\u2019Interessato potranno essere trattati anche per finalit\u00e0 di promozione commerciale, per indagini e ricerche di mercato con riguardo a Servizi\/Prodotti che il Titolare offre solo se l\u2019Interessato ha autorizzato il trattamento e non si oppone a questo.<\/p>\n<p>Tale trattamento pu\u00f2 avvenire, in modo automatizzato, con le seguenti modalit\u00e0:<\/p>\n<p>&#8211; e-mail;<\/p>\n<p>&#8211; sms;<\/p>\n<p>&#8211; contatto telefonico e pu\u00f2 essere svolto:<\/p>\n<p>qualora l\u2019Interessato non abbia revocato il suo consenso per l\u2019utilizzo dei dati;<\/p>\n<p>qualora, nel caso in cui il trattamento si svolga mediante contatto con operatore telefonico, l\u2019Interessato non sia iscritto al registro delle opposizioni di cui al D.P.R. n. 178\/ 2010;<\/p>\n<p>Base giuridica di tali trattamenti \u00e8 il consenso prestato dall\u2019Interessato preliminarmente al trattamento stesso, il quale \u00e8 revocabile dall\u2019interessato liberamente ed in qualsiasi momento (vedasi Sezione III).<\/p>\n<p>La sicurezza informatica<\/p>\n<p>Il Titolare, in linea con quanto previsto dal Considerando 49 del GDPR, tratta, anche per mezzo dei suoi fornitori (terzi e\/o destinatari), i dati personali dell\u2019Interessato relativi al traffico in misura strettamente necessaria e proporzionata per garantire la sicurezza delle reti e dell&#8217;informazione, vale a dire la capacit\u00e0 di una rete o di un sistema d&#8217;informazione di resistere, a un dato livello di sicurezza, a eventi imprevisti o atti illeciti o dolosi che compromettano la disponibilit\u00e0, l&#8217;autenticit\u00e0, l&#8217;integrit\u00e0 e la riservatezza dei dati personali conservati o trasmessi.<\/p>\n<p>Il Titolare informer\u00e0 prontamente gli Interessati, qualora sussista un particolare rischio di violazione dei loro dati fatti salvi gli obblighi derivanti da quanto previsto dall\u2019art. 33 del GDPR relativo alle notifiche di violazione di dati personali.<\/p>\n<p>La profilazione<\/p>\n<p>I dati personali dell\u2019Interessato potranno essere trattati anche per finalit\u00e0 di profilazione (quali analisi dei dati trasmessi e dei Servizi\/Prodotti prescelti, proporre messaggi pubblicitari e\/o proposte commerciali in linea con le scelte manifestate dagli utenti medesimi) esclusivamente nel caso in cui l\u2019Interessato abbia fornito un consenso esplicito e informato. Base giuridica di tali trattamenti \u00e8 il consenso prestato dall\u2019Interessato preliminarmente al trattamento stesso, il quale \u00e8 revocabile dall\u2019Interessato liberamente ed in qualsiasi momento (vedasi Sezione III).<\/p>\n<p>Dove trattiamo i dati dell\u2019Interessato<\/p>\n<p>I dati personali dell\u2019Interessato sono conservati in archivi cartacei, informatici e telematici prevalentemente situati in paesi nei quali \u00e8 applicato il GDPR (paesi UE).<\/p>\n<p>Per quanto tempo vengono conservati i dati dell\u2019Interessato? (art. 13, 2\u00b0 comma, lett. a GDPR)<\/p>\n<p>A meno che questi non esprima esplicitamente la propria volont\u00e0 di rimuoverli, i dati personali dell\u2019Interessato saranno conservati fino a che saranno necessari rispetto alle legittime finalit\u00e0 per le quali sono stati raccolti.<\/p>\n<p>In particolare, saranno conservati per tutta la durata della sua iscrizione anagrafica e comunque non oltre un periodo massimo di 12 (dodici) mesi di sua inattivit\u00e0, ovvero qualora, entro tale termine, non risultino associati dei Servizi e\/o acquistati dei Prodotti mediante l\u2019anagrafica stessa.<\/p>\n<p>Nel caso di dati forniti al Titolare per le finalit\u00e0 di promozione commerciale per servizi diversi da quelli gi\u00e0 acquisiti dall\u2019Interessato, per le quali inizialmente Egli abbia prestato il consenso, questi saranno conservati per 24 mesi, salvo revoca del consenso prestato.<\/p>\n<p>Nel caso di dati forniti al Titolare per le finalit\u00e0 di profilazione, questi saranno conservati per 12 mesi, salvo sempre revoca del consenso prestato.<\/p>\n<p>Occorre inoltre aggiungere che, nel caso in cui un utente inoltri ad CRONDRIVE\u00a0 dati personali non richiesti o non necessari al fine dell\u2019esecuzione della prestazione richiesta ovvero all\u2019erogazione di un servizio ad essa strettamente connessa, CRONDRIVE\u00a0 non potr\u00e0 essere considerata titolare di questi dati, e provveder\u00e0 alla loro cancellazione nel pi\u00f9 breve tempo possibile.<\/p>\n<p>Altres\u00ec, i dati personali saranno in ogni caso conservati per l\u2019adempimento degli obblighi (es. fiscali e contabili) che permangono anche dopo la cessazione del contratto (art. 2220 c.c.); per tali fini il Titolare conserver\u00e0 solo i dati necessari al relativo perseguimento.<\/p>\n<p>RACCOLTA DI DATI PERSONALI<\/p>\n<p>Raccolta di Dati Personali: CRONDRIVE\u00a0 potr\u00e0 raccogliere Dati Personali su di Lei dalle seguenti fonti:<\/p>\n<p>\u203a Dati che l\u2019utente fornisce: CRONDRIVE\u00a0 potr\u00e0 ottenere Dati Personali allorch\u00e9 Lei stesso ce li fornisca (e.g. quando contatta CRONDRIVE\u00a0 anche a mezzo email).<\/p>\n<p>\u203a Dati raccolti nel corso del Rapporto: CRONDRIVE\u00a0 potr\u00e0 raccogliere o ottenere Dati Personali su di Lei nel normale corso del rapporto (ad es. nell\u2019ambito dello svolgimento delle attivit\u00e0 istituzionali di CRONDRIVE, quali le attivit\u00e0 di innovazione, export, sviluppo del territorio e marketing).<\/p>\n<p>\u203a Dati che Lei rende pubblici: CRONDRIVE\u00a0 potr\u00e0 raccogliere o ottenere i Dati Personali che Lei decide di rendere pubblici, anche attraverso i social media (e.g. CRONDRIVE\u00a0 potr\u00e0 raccogliere informazioni dal(i) Suo(i) profilo(i) social, qualora Lei scriva un \u201cpost\u201d pubblico su CRONDRIVE).<\/p>\n<p>\u203a Dati in rapporto al Sito: CRONDRIVE\u00a0 potr\u00e0 raccogliere o ottenere i Dati Personali su di Lei quando visita un Sito di CRONDRIVE\u00a0 ovvero utilizza una delle funzionalit\u00e0 o risorse disponibili sul o attraverso il Sito(i).<\/p>\n<p>\u203a Informazioni di registrazione: CRONDRIVE\u00a0 potr\u00e0 raccogliere o ottenere i Dati Personali quando Lei utilizzai, ovvero si registra per usare una delle funzionalit\u00e0 o risorse disponibili sul o attraverso il Sito(i).<\/p>\n<p>\u203a Informazioni in rapporto ai Contenuti: nel caso in cui Lei decidesse di interagire con i contenuti di terze parti nell\u2019ambito di utilizzo del Sito(i), CRONDRIVE\u00a0 potr\u00e0 ricevere Dati Personali riferibili a Lei sia direttamente sia dalla parte terza che fornisce i contenuti.<\/p>\n<p>\u203a Informazioni da terze parti: CRONDRIVE\u00a0 potr\u00e0 raccogliere o ottenere i Dati Personali su di Lei da terze parti che le forniscono a CRONDRIVE, incluse terze parti che forniscono contenuti o le pubblicit\u00e0.<\/p>\n<p>CATEGORIE DI DATI PERSONALI CHE CRONDRIVE\u00a0 POTR\u00c0 TRATTARE<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 potr\u00e0 trattare le seguenti categorie di Dati Personali su di Lei nella misura in cui tale trattamento risulti strettamente necessario in relazione alle finalit\u00e0 di trattamento definite nella presente Data Protection Policy:<\/p>\n<p>\u203a Informazioni personali: nome(i) di battesimo; nome correntemente utilizzato; nickname e soprannomi, fotografia.<\/p>\n<p>\u203a Informazioni demografiche: sesso; data di nascita\/et\u00e0; nazionalit\u00e0; titolo; e preferenze linguistiche.<\/p>\n<p>\u203a Informazioni di contatto: indirizzo; numero di telefono; indirizzo email; e informazioni dal(i) Suo(i) profilo(i) pubblico sui social media.<\/p>\n<p>\u203a Informazioni di pagamento: registrazione delle fatture; registrazione dei pagamenti; indirizzo di fatturazione; modalit\u00e0 di pagamento; numero di conto corrente bancario o numero di carta di credito; nominativo del titolare della carta o del titolare del conto; informazioni sulla sicurezza della carta card o del conto; periodo di validit\u00e0 della carta e data di scadenza; ammontare del pagamento; data del pagamento; registrazione degli assegni.<\/p>\n<p>\u203a Dati in rapporto al Sito(i): informazioni sui servizi e attivit\u00e0 di CRONDRIVE ; impostazioni; indirizzo IP; impostazioni della lingua; data e orario; statistiche sull\u2019utilizzo del Sito(i) e\/o Applicazione(i); impostazioni del Sito(i) e\/o Applicazione(i); data e orario di connessione al Sito(i) e\/o Applicazione(i); dati relativi alla localizzazione, e altre informazioni relative alle comunicazioni tecniche; username; password; informazioni di sicurezza in fase di login; dati di utilizzo; informazioni aggregate per finalit\u00e0 statistiche.<\/p>\n<p>\u203a Dati sui contenuti e le pubblicit\u00e0: registrazione delle Sue iterazioni con i servizi online di pubblicit\u00e0 e i Contenuti, registrazione delle pubblicit\u00e0 e dei Contenuti mostrati sulle pagine o sulle Applicazioni visibili a Lei, e di qualunque interazione che potrebbe aver avuto con detti contenuti o pubblicit\u00e0.<\/p>\n<p>\u203a Visualizzazioni e opinioni: qualunque visualizzazione o opinione che decida di inviare a CRONDRIVE\u00a0 (e.g. attraverso sondaggi o votazioni, compilazione di moduli per i feedback, o valutazione fatta sulle Applicazioni in piattaforme di acquisto digitale di applicazioni di terze parti) o \u201cpostati\u201d pubblicamente sui social media.<\/p>\n<p>\u203a Dati Non Personali: quando Lei utilizza i servizi di CRONDRIVE, CRONDRIVE\u00a0 potr\u00e0 altres\u00ec raccogliere informazioni che, per s\u00e9 stesse o in combinazione con altre analoghe informazioni, non possono essere utilizzate per la Sua identificazione personale, ovvero per contattarLa personalmente (\u201cDati Non Personali\u201d). I Dati Non Personali includono a informazioni sull\u2019utilizzo del Sito(i) e delle Applicazione(i).<\/p>\n<p>Dati Personali di bambini di et\u00e0 inferiore ai sedici (16) anni.<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 si impegna nella protezione dei Dati Personali dei bambini e non raccoglie deliberatamente alcun dato Personale relativo a detti minori per alcun motivo, n\u00e9 accetter\u00e0 registrazioni provenienti da detti minori.<\/p>\n<p>In taluni casi, in particolare allorch\u00e9 le informazioni vengano raccolte con modalit\u00e0 elettroniche, CRONDRIVE\u00a0 potr\u00e0 non essere in grado di stabilire se l\u2019informazione \u00e8 stata raccolta da bambini di et\u00e0 inferiore agli anni sedici (16) e CRONDRIVE\u00a0 tratter\u00e0 tale informazione come se la stessa fosse stata fornita da un adulto.<\/p>\n<p>Qualora CRONDRIVE\u00a0 fosse informata del fatto che un bambino di et\u00e0 inferiore agli anni sedici (16) ha fornito un Dato Personale, CRONDRIVE\u00a0 si impegner\u00e0 a ogni ragionevole sforzo dal punto di vista commerciale al fine di rimuovere tale informazione.<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 invita genitori e tutori a partecipare a tutte le attivit\u00e0 online dei propri bambini e a evitare che questi forniscano Dati Personali attraverso gli Smart Services. CRONDRIVE\u00a0 NEGA ESPRESSAMENTE OGNI RESPONSABILITA\u2019 O PRETESA IN RELAZIONE ALL\u2019USO, OVVERO ABUSO, DI DETTE FUNZIONALITA\u2019 DA PARTE DEI BAMBINI IN VIOLAZIONE DELLA PRESENTE DATA PROTECTION POLICY.<\/p>\n<p>\u203a Cookies e altre tecnologie di tracciamento. Talvolta, il Sito(i) e\/o altri Contenuti o Applicazioni possono utilizzare \u201ccookies\u201d ovvero altre tecnologie (quali browser cookies, flash cookies, e web beacons). Un \u201ccookie\u201d \u00e8 un piccolo file di dati posto all\u2019interno del Sito(i) e\/o dei Contenuti\/Applicazioni conservato localmente all\u2019interno dei medesimi. Tali tecnologie aiutano CRONDRIVE\u00a0 a meglio comprendere il comportamento dell\u2019utilizzatore, fornendo informazioni sulle sezioni, i contenuti che Lei ha visualizzato o cui Lei ha fatto accesso e aiutano a rendere la Sua esperienza con il Sito pi\u00f9 utili e personalizzate. Inoltre, i \u201ccookie\u201d e le altre tecnologie che possono essere utilizzate per raccogliere informazioni sulle Sue attivit\u00e0 online nel tempo e su siti web e servizi di terze parti.<\/p>\n<p>FONDAMENTO GIURIDICO PER IL TRATTAMENTO DI DATI SENSIBILI AI SENSI DELL\u2019ART. 6, REG. 2016\/679\/UE<\/p>\n<p>Nel trattamento dei Suoi Dati Personali con riferimento alle finalit\u00e0 di trattamento definite nella presente Data Protection Policy, CRONDRIVE\u00a0 potr\u00e0 fare riferimento a uno o pi\u00f9 dei fondamenti giuridici che seguono, a seconda delle circostanze:<\/p>\n<p>\u203a Consenso: CRONDRIVE\u00a0 potr\u00e0 trattare i Suoi Dati personali allorch\u00e9 CRONDRIVE\u00a0 avr\u00e0 ottenuto il Suo previo, espresso consenso a Trattamento (il presente fondamento giuridico \u00e8 utilizzato esclusivamente con riferimento al Trattamento che risulta interamente volontario \u2013 non \u00e8 utilizzato per i Trattamenti necessari o in qualunque modo obbligatori);<\/p>\n<p>\u203a Esigenze contrattuali: CRONDRIVE\u00a0 potr\u00e0 Trattare i Suoi Dati Personali allorch\u00e9 il Trattamento \u00e8 necessario in relazione a un contratto che Lei stipula con CRONDRIVE;<\/p>\n<p>\u203a Adempimento alla legge applicabile: CRONDRIVE\u00a0 potr\u00e0 Trattare i Suoi Dati Personali allorch\u00e9 il Trattamento \u00e8 richiesto dalla legge applicabile;<\/p>\n<p>\u203a Interessi fondamentali: CRONDRIVE\u00a0 potr\u00e0 Trattare i Suoi Dati Personali allorch\u00e9 il Trattamento \u00e8 necessario per proteggere gli interessi fondamentali di una persona fisica; ovvero<\/p>\n<p>\u203a Interessi legittimi: CRONDRIVE\u00a0 potr\u00e0 Trattare i Suoi Dati Personali allorch\u00e9 CRONDRIVE\u00a0 ha un interesse legittimo a procedere nel Trattamento per finalit\u00e0 gestionali, operative ovvero di promozione dell\u2019attivit\u00e0 e allorch\u00e9 detto interesse legittimo non sia superato da Suoi interessi, diritti fondamentali o libert\u00e0.<\/p>\n<p>DATI SENSIBILI<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 non intende raccogliere o in altro modo Trattare i Suoi Dati Sensibili nel normale corso della sua attivit\u00e0. Qualora, per qualsivoglia ragione, diventasse necessario Trattare i Suoi Dati Sensibili, CRONDRIVE\u00a0 far\u00e0 riferimento a uno o pi\u00f9 dei fondamenti giuridici che seguono:<\/p>\n<p>\u203a Adempimento alla legge applicabile: CRONDRIVE\u00a0 potr\u00e0 Trattare i Suoi Dati Sensibili allorch\u00e9 il Trattamento \u00e8 richiesto ovvero consentito dalla legge applicabile;<\/p>\n<p>\u203a Individuazione e prevenzione di un reato: CRONDRIVE\u00a0 potr\u00e0 Trattare i Suoi Dati Sensibili allorch\u00e9 il Trattamento \u00e8 necessario per l\u2019individuazione e la prevenzione di un reato (inclusa la prevenzione di truffe);<\/p>\n<p>\u203a Creazione, esercizio o difesa di un diritto: CRONDRIVE\u00a0 potr\u00e0 Trattare i Suoi Dati Sensibili allorch\u00e9 il Trattamento \u00e8 necessario per la creazione, l\u2019esercizio o la difesa di un diritto; ovvero<\/p>\n<p>\u203a Consenso: CRONDRIVE\u00a0 potr\u00e0 Trattare i Suoi Dati Sensibili qualora CRONDRIVE abbia ottenuto, conformemente alla legge applica- bile, il Suo previo, espresso consenso al Trattamento dei Suoi Dati Sensibili (il presente fondamento giuridico \u00e8 utilizzato esclusivamente con riferimento al Trattamento che risulta interamente volontario \u2013 non \u00e8 utilizzato per i Trattamenti necessari o in qualunque modo obbligatori).<\/p>\n<p>COME CRONDRIVE\u00a0 USA LE INFORMAZIONI CHE HA RACCOLTO<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 potr\u00e0 trattare i Suoi dati Personali per le seguenti finalit\u00e0:<\/p>\n<p>\u203a Fornitura del Sito(i)i e Applicazione(i): fornitura di Sito(i), Applicazione(i) e Contenuti; registrazione del Suo account; fornire servizi che ha richiesto; fornire a Lei materiale promozionale a Sua richiesta; comunicare con Lei in relazione a detti servizi; funzionamento e gestione del Sito(i) e Applicazione(i); fornitura di Contenuti; mostrarti pubblicit\u00e0 o altre informazioni; comunicare e interagire con Lei attraverso il Sito e le Applicazioni.<\/p>\n<p>\u203a Comunicazioni con Lei: comunicazioni con Lei attraverso ogni mezzo (inclusi email, telefono, messaggi di testo, social media, post ovvero di persona) relative a nuovi elementi e altre informazioni rispetto alle quali Lei potrebbe essere interessato, posto che dette comunicazioni siano fornite a Lei in conformit\u00e0 alla legge applicabile; mantenere o aggiornare le Sue informazioni di contatto ove opportuno; e posto l\u2019ottenimento del Suo previo consenso sulla decisione di \u201coptin\u201d ove richiesto.<\/p>\n<p>\u203a Comunicazioni e operazioni IT: gestione dei sistemi di comunicazione; operazioni sulla sicurezza dei sistemi IT; controlli sulla sicurezza IT.<\/p>\n<p>\u203a Gestione finanziaria: vendite; finanza; controlli societari.<\/p>\n<p>\u203a Sondaggi e votazioni: confronto con Lei al fine di ottenere la Sua opinione sui servizi di CRONDRIVE<\/p>\n<p>\u203a Attivit\u00e0 investigative: individuazione, investigazione e prevenzione di violazioni di norme e reati conformemente alla legge applicabile.<\/p>\n<p>\u203a Procedimenti legali: creazione, esercizio e difesa di diritti.<\/p>\n<p>\u203a Adeguamento alla legge: adeguamento agli obblighi di legge e regolatori conformemente alla legge applicabile.<\/p>\n<p>\u203a Miglioramento del Sito e delle Applicazioni: identificazione di problemi con il Sito(i) e le applicazioni; pianificazione di miglioramenti del Sito(i) e delle applicazioni; e creazione di nuovi Sito(i) e applicazioni.<\/p>\n<p>\u203a Dati Non Personali: CRONDRIVE\u00a0 potr\u00e0 usare dati Non Personali per finalit\u00e0 interne, quali ad esempio analisi statistiche. CRONDRIVE\u00a0 si riserva il diritto di usare o divulgare aggregati e\/o Dati non Personali in ogni maniera che ritiene opportuna per fini istituzionali e Lei riconosce e presta consenso a tal fine. CRONDRIVE\u00a0 potr\u00e0 altres\u00ec utilizzare dati diagnostici (che non identifichino Lei e non contengano Dati Personali) al fine di migliorare il funzionamento del Sito(i) e delle applicazioni.<\/p>\n<p>\u203a Combinazione di Informazioni. CRONDRIVE\u00a0 potr\u00e0 combinare i Dati Personali e i Dati Non Personali raccolti al fine di fornire e migliorare i servizi offerti. Di tanto in tanto, CRONDRIVE\u00a0 potr\u00e0 altres\u00ec, trasferire o unire Dati Personali raccolti off- line con i database online ovvero archiviare in formato elettronico informazioni raccolte off-line. CRONDRIVE\u00a0 potr\u00e0 altres\u00ec combinare i Dati Personali raccolti online con le informazioni rese disponibili da altre fonti. Qualora CRONDRIVE\u00a0 combini Dati Non Personali con Dati personali, l\u2019informazione cos\u00ec combinata verr\u00e0 trattata come Dato Personale conformemente alla presente Data Protection Policy per tutto il tempo in cui gli stessi dati resteranno combinati.<\/p>\n<p>Contattare<\/p>\n<p>Quando ci contattate (ad es. tramite modulo di contatto, E-Mail, telefono o tramite social media), i dettagli dell&#8217;utente vengono utilizzati per elaborare la richiesta di contatto e come elaborarlo in conformit\u00e0 con l&#8217;articolo 6 (1) illuminato. b) GDPR. Le informazioni degli utenti possono essere memorizzate in un sistema di gestione delle relazioni con i clienti (&#8220;sistema CRM&#8221;) o in un&#8217;organizzazione di richiesta analoga.<\/p>\n<p>Cancelleremo le richieste se non sono pi\u00f9 necessarie. Controlliamo il requisito ogni due anni; Inoltre, si applicano gli obblighi legali di archiviazione.<\/p>\n<p>Commenti e post<\/p>\n<p>Se gli utenti lasciano commenti o altri post, i loro indirizzi IP possono basarsi sui nostri interessi legittimi ai sensi dell&#8217;articolo 6, paragrafo 1, lett. (GDPR) per 7 giorni. Questo viene fatto per la nostra sicurezza se qualcuno lascia contenuti illegali in commenti e post (insulti, propaganda politica proibita, ecc.). In questo caso, possiamo essere perseguitati per il commento o il contributo noi stessi e siamo quindi interessati all&#8217;identit\u00e0 dell&#8217;autore.<\/p>\n<p>Inoltre, ci riserviamo il diritto di utilizzare l&#8217;articolo 6 (1) illuminato sulla base dei nostri interessi legittimi. GDPR per elaborare le informazioni degli utenti per il rilevamento dello spam.<\/p>\n<p>Sottoscrizioni di commenti<\/p>\n<p>I commenti di follow-up possono essere fatti dagli utenti con il loro consenso all&#8217;articolo 6 (1) illuminato. (GDPR). Gli utenti riceveranno un&#8217;e-mail di conferma per verificare che siano il proprietario dell&#8217;indirizzo email che entrano. Gli utenti possono rifiutare esplicitamente le sottoscrizioni di commenti in corso in qualsiasi momento. L&#8217;E-mail di conferma includer\u00e0 suggerimenti sulle opzioni di revoca. Ai fini della prova del consenso dell&#8217;utente, memorizziamo il punto di registrazione cos\u00ec come l&#8217;indirizzo IP degli utenti ed eliminiamo queste informazioni quando l&#8217;utente rinuncia all&#8217;abbonamento.<\/p>\n<p>Puoi annullare la ricezione del nostro menu di abbonamento in qualsiasi momento, cio\u00e8 Resistete ai loro consensi. Potremmo archiviare gli indirizzi inviati via email per un massimo di tre anni sulla base dei nostri interessi legittimi prima di eliminarli per dimostrare il consenso preventivo. Il trattamento di questi dati \u00e8 limitato allo scopo di una possibile difesa contro i reclami. Una richiesta di cancellazione individuale \u00e8 possibile in qualsiasi momento, a condizione che la precedente esistenza del consenso sia confermata allo stesso tempo.<\/p>\n<p>Newsletter<\/p>\n<p>Con i seguenti avvisi, ti informiamo sui contenuti della nostra newsletter, nonch\u00e9 la procedura di registrazione, spedizione e valutazione statistica, nonch\u00e9 i tuoi diritti di opposizione. Iscrivendoti alla nostra newsletter, accetti la ricezione e le procedure descritte.<\/p>\n<p>Contenuto della newsletter: inviamo newsletter, E-mail e altre notifiche elettroniche con informazioni pubblicitarie (&#8220;newsletter&#8221;) solo con il consenso dei destinatari o un&#8217;autorizzazione legale. Se il suo contenuto \u00e8 specificatamente descritto come parte di una registrazione per la newsletter, essi sono decisivi per il consenso degli utenti. Inoltre, le nostre newsletter contengono informazioni sui nostri servizi e noi.<\/p>\n<p>Credenziali di registrazione: per iscriversi alla newsletter, \u00e8 sufficiente fornire il proprio indirizzo e-mail. Come opzione, ti chiediamo di fornire un nome per il contatto personale nella newsletter.<\/p>\n<p>Recesso\/revoca-\u00e8 possibile annullare la ricezione della nostra newsletter in qualsiasi momento, cio\u00e8 Resistete ai loro consensi. Potremmo archiviare gli indirizzi inviati via email per un massimo di tre anni sulla base dei nostri interessi legittimi prima di eliminarli per dimostrare il consenso preventivo. Il trattamento di questi dati \u00e8 limitato allo scopo di una possibile difesa contro i reclami. Una richiesta di cancellazione individuale \u00e8 possibile in qualsiasi momento, a condizione che la precedente esistenza del consenso sia confermata allo stesso tempo.<\/p>\n<p>Google Analytics<\/p>\n<p>In base ai nostri interessi legittimi (vale a dire l&#8217;interesse per l&#8217;analisi, l&#8217;ottimizzazione e il funzionamento economico della nostra offerta online ai sensi dell&#8217;articolo 6 (1)) del GDPR), utilizziamo Google Analytics, un servizio di analisi Web di Google LLC (&#8220;Google&#8221;). Google utilizza i cookie. Le informazioni generate dal cookie sull&#8217;utilizzo dell&#8217;offerta online da parte degli utenti vengono solitamente trasmesse a un server di Google negli Stati Uniti e l\u00ec memorizzate.<\/p>\n<p>Google \u00e8 certificata ai sensi del Privacy Shield Agreement e offre quindi una garanzia per conformarsi alla legge europea sulla protezione dei dati (https:\/\/www.privacyshield.gov\/participant?id=a2zt000000001L5AAI&amp;status=Active).<\/p>\n<p>Google utilizzer\u00e0 queste informazioni per nostro conto per valutare l&#8217;utilizzo della nostra offerta online da parte degli utenti, compilare report sulle attivit\u00e0 all&#8217;interno di questa offerta online e fornire ulteriori informazioni sull&#8217;utilizzo di questa offerta online e sull\u2019Internet utilizzare servizi correlati per fornirci. I profili utente pseudonimi possono essere creati dai dati elaborati.<\/p>\n<p>Usiamo solo Google Analytics con anonimizzazione IP abilitata. Ci\u00f2 significa che l&#8217;indirizzo IP degli utenti viene abbreviato da Google all&#8217;interno degli Stati membri dell&#8217;Unione europea o in altri Stati contraenti dell&#8217;accordo sullo spazio economico europeo. Solo in casi eccezionali l&#8217;indirizzo IP completo verr\u00e0 trasmesso a un server di Google negli Stati Uniti e l\u00ec abbreviato.<\/p>\n<p>L&#8217;indirizzo IP trasmesso dal browser dell&#8217;utente non verr\u00e0 unito ad altri dati di Google. Gli utenti possono impedire l&#8217;archiviazione dei cookie modificando di conseguenza il software del browser; Gli utenti possono anche impedire la raccolta dei dati generati dal cookie e relativi al suo utilizzo dell&#8217;offerta online a Google, cos\u00ec come l&#8217;elaborazione di tali dati da parte di Google utilizzando il plugin del browser disponibile al seguente link. Scaricare e installare: http:\/\/tools.google.com\/dlpage\/gaoptout?hl=de.<\/p>\n<p>Per ulteriori informazioni sull&#8217;utilizzo dei dati da parte di Google, l&#8217;assunzione e l&#8217;obiezione, vedere l&#8217;informativa sulla privacy di Google (https:\/\/policies.google.com\/technologies\/ads) e le impostazioni per la presentazione di Pubblicit\u00e0 di Google (https:\/\/adssettings.google.com\/authenticated).<\/p>\n<p>I dati personali degli utenti saranno cancellati o anonimizzati dopo 14 mesi.<\/p>\n<p>Pixel di Facebook, pubblico personalizzato e conversione di Facebook<\/p>\n<p>All&#8217;interno della nostra offerta online, a causa dei nostri legittimi interessi nell&#8217;analisi, ottimizzazione e funzionamento economico della nostra offerta online e per questi scopi, il cosiddetto &#8220;pixel di Facebook&#8221; del social network Facebook, che \u00e8 supportato da Facebook Inc., 1 Hacker Way, Menlo Park, CA 94025, USA, o se hai sede nell&#8217;UE, Facebook Ireland Ltd., 4 Grand Canal Square, Grand Canal Harbour, Dublin 2, Irlanda (&#8220;Facebook&#8221;).<\/p>\n<p>Facebook \u00e8 certificata ai sensi del Privacy Shield Agreement e offre quindi una garanzia per conformarsi alla legge europea sulla protezione dei dati (https:\/\/www.privacyshield.gov\/participant?id=a2zt0000000GnywAAC&amp;status=Active).<\/p>\n<p>Con l&#8217;aiuto del pixel di Facebook, Facebook \u00e8 in grado di determinare i visitatori della nostra offerta online come target group per la presentazione degli annunci (le cosiddette &#8220;inserzioni di Facebook&#8221;). Di conseguenza, usiamo il pixel di Facebook per visualizzare le inserzioni di Facebook che abbiamo attivato solo agli utenti di Facebook che hanno anche mostrato un interesse per la nostra offerta online o che hanno determinate caratteristiche (ad esempio, interessi in determinati argomenti o Prodotti che sono determinati dai siti Web visitati), che trasmettiamo a Facebook (cosiddetto &#8220;pubblico personalizzato&#8221;). Con l&#8217;aiuto del pixel di Facebook, vogliamo anche fare in modo che le nostre inserzioni di Facebook siano in linea con il potenziale interesse degli utenti e non abbiano una seccatura. Con l&#8217;aiuto del pixel di Facebook, possiamo anche comprendere l&#8217;efficacia delle inserzioni di Facebook per scopi statistici e di ricerca di mercato, in cui vediamo se gli utenti sono stati inoltrati al nostro sito Web dopo aver cliccato su un annuncio di Facebook (c.d. &#8221; Conversione &#8220;).<\/p>\n<p>Facebook elabora i dati come parte della politica di utilizzo dei dati di Facebook. Di conseguenza, note generali sulla visualizzazione delle inserzioni di Facebook, nella politica di utilizzo dei dati di Facebook: https:\/\/www.facebook.com\/policy.php. Per informazioni speciali e dettagli sul pixel di Facebook e su come funziona, visita la sezione della Guida di Facebook: https:\/\/www.facebook.com\/business\/help\/651294705016616.<\/p>\n<p>Puoi obiettare all&#8217;acquisizione dal pixel di Facebook e utilizzare i tuoi dati per visualizzare le inserzioni di Facebook. Per impostare i tipi di annunci che vedi all&#8217;interno di Facebook, puoi visualizzare la pagina impostata da Facebook e seguire le impostazioni degli annunci basati sull&#8217;utilizzo: https:\/\/www.facebook.com\/settings?tab=ads. Le impostazioni vengono effettuate su base indipendente dalla piattaforma, ovvero vengono applicate a tutti i dispositivi, ad esempio computer desktop o dispositivi mobili.<\/p>\n<p>L&#8217;utente pu\u00f2 inoltre opporsi all&#8217;utilizzo dei cookie per la misurazione della portata e per scopi pubblicitari tramite la pagina di disattivazione dell&#8217;iniziativa Network Advertising (http:\/\/optout.networkadvertising.org\/) e in aggiunta al sito Web statunitense (http:\/\/www.aboutads.info\/choices) o al sito web europeo (http:\/\/www.youronlinechoices.com\/uk\/your-ad-choices\/ ).<\/p>\n<p>&nbsp;<\/p>\n<p>Presenza online sui social media<\/p>\n<p>Manteniamo la presenza online all&#8217;interno di social network e piattaforme al fine di comunicare con i clienti, i potenziali clienti e gli utenti che vi sono attivi e di informarli sui nostri servizi. Quando si chiamano le rispettive reti e piattaforme, si applicano i termini e le condizioni e le politiche di trattamento dei dati dei rispettivi operatori.<\/p>\n<p>Se non diversamente specificato nel contesto della nostra politica sulla privacy, trattiamo i dati degli utenti fino a quando comunicano con noi all&#8217;interno dei social network e piattaforme, ad esempio scrivere post sulla nostra presenza online o inviarci messaggi.<\/p>\n<p>Se non diversamente specificato nel contesto della nostra politica sulla privacy, trattiamo i dati degli utenti fino a quando comunicano con noi all&#8217;interno dei social network e piattaforme, ad esempio scrivere post sulla nostra presenza online o inviarci messaggi.<\/p>\n<p>Integrazione di servizi e contenuti di terze parti<\/p>\n<p>All&#8217;interno della nostra offerta online, impostiamo il contenuto o il servizio offerte di Fornitori di terze parti per integrare i loro contenuti e servizi, come video o font (di seguito uniformemente come &#8220;contenuto&#8221;).<\/p>\n<p>Ci\u00f2 presuppone sempre che i fornitori di terze parti di questo contenuto percepiscano l&#8217;indirizzo IP degli utenti, dal momento che non sarebbero in grado di inviare il contenuto al proprio browser senza l&#8217;indirizzo IP. L&#8217;indirizzo IP \u00e8 quindi richiesto per la presentazione di questo contenuto. Facciamo ogni sforzo per utilizzare solo i contenuti i cui rispettivi fornitori utilizzano solo l&#8217;indirizzo IP per recapitare il contenuto. I fornitori di terze parti possono anche utilizzare i cosiddetti pixel tag (grafica invisibile, noto anche come &#8220;Web beacon&#8221;) per scopi statistici o di marketing. I &#8220;pixel tag&#8221; consentono di analizzare le informazioni sulle pagine di questo sito Web. Le informazioni pseudonime possono anche essere memorizzate nei cookie sul dispositivo dell&#8217;utente e, tra le altre cose, informazioni tecniche sul browser e sul sistema operativo, siti Web di riferimento, tempo di visita e altre informazioni sull&#8217;utilizzo della nostra offerta online Cos\u00ec come associato a tali informazioni da altre fonti.<\/p>\n<p>COME CRONDRIVE\u00a0 CONDIVIDE E DIVULGA LE INFORMAZIONI<\/p>\n<p>Pu\u00f2 accadere che CRONDRIVE\u00a0 condivide le informazioni di cui alla presente Data Protection Policy e la sezione che segue descrive il modo in cui CRONDRIVE\u00a0 condivide tali informazioni. CRONDRIVE\u00a0 divulgher\u00e0 i Suoi Dati Personali solo e nella misura in cui \u00e8 necessario: (i) per fornire i servizi che ha richiesto; (ii) per adeguamento alla legge applicabile; (iii) per creare, esercitare o difendere un diritto di CRONDRIVE; (iv) nella misura necessaria in relazione alla vendita o riorganizza- zione di una parte sostanziale della attivit\u00e0 di CRONDRIVE<\/p>\n<p>\u203a Dati Personali e Dati Non-Personali. CRONDRIVE\u00a0 potr\u00e0 condividere Dati Personali e Dati Non-Personali come segue:<\/p>\n<p>\u203a Con i dipendenti, controparti contrattuali, al fine di aiutare a fornire o migliorare i servizi.<\/p>\n<p>\u203a Con i consulenti professionali di CRONDRIVE<\/p>\n<p>\u203a Con terze parti e loro relativi consulenti in relazione a fusioni, acquisizioni, bancarotta, scioglimento, riorganizzazione, vendita totale o parziale degli asset di CRONDRIVE, attivit\u00e0 finanziarie, cessione totale o parziale delle attivit\u00e0 di CRONDRIVE, ovvero transazioni o procedure similari, nonch\u00e9 attivit\u00e0 ad esse preliminari (e.g. due diligence).<\/p>\n<p>\u203a Allorch\u00e9 richiesto o consentito dalle leggi e regolamenti applicabili.<\/p>\n<p>\u203a Con ogni parte rilevante ai fini di prevenzione, investigazione, individuazione o azione rispetto a reati ovvero in esecuzione di condanne penali, inclusa la tutela contro e la prevenzione di minacce alla sicurezza pubblica.<\/p>\n<p>\u203a Con ogni parte rilevante, autorit\u00e0 garante o tribunale, nella misura necessaria per la costituzione, l\u2019esercizio e la difesa di diritti.<\/p>\n<p>\u203a Con autorit\u00e0 pubbliche o private, su richiesta, ovvero al fine di segnalare ogni violazione, attuale o potenziale, alla legge e ai regolamenti applicabili.<\/p>\n<p>\u203a Con terze parti accuratamente selezionate, inclusi fornitori, qualora necessario per fornire a CRONDRIVE\u00a0 un servizio o per eseguire una funzione per il conto di CRONDRIVE\u00a0 in relazione al Sito(i) ovvero ad un servizio di CRONDRIVE Ogni divulgazione di un Suo Dato Personale a una terza parte accuratamente selezionata o a una qualsivoglia terza parte menzionata nella presente Data Protection Policy, CRONDRIVE\u00a0 si adeguer\u00e0 alla normativa in materia di protezione dei dati personali, assicurandosi che la terza parte abbia posto in essere tutte le misure per mantenere i Suoi dati sicuri, non utilizzi i Suoi Dati Personali per finalit\u00e0 diverse e ulteriori rispetto a quelle specificate e conformemente ai scopi indicati nella presente Data Protection Policy.<\/p>\n<p>\u203a Con altre terze parti esclusivamente a Sua discrezione e con il Suo espresso consenso e per le finalit\u00e0 da Lei richieste.<\/p>\n<p>MATERIALI DI TERZE PARTI<\/p>\n<p>Terze parti che offrono Applicazioni o Materiali possono raccogliere dati Personali ovvero Dati Non Personali allorch\u00e9 Lei accede alle loro Applicazioni e Materiali sui servizi. CRONDRIVE\u00a0 non \u00e8 responsabile per la raccolta di dati e le privacy policy in uso a tali terze parti o per i loro servizi, e loro potrebbero raccogliere dati su di Lei e potrebbero condividerli con CRONDRIVE\u00a0 e\/o altri. Dette terze parti e i loro servizi possono altres\u00ec tracciare Lei nel tempo e nello spazio, sottoporre le loro proprie pubblicit\u00e0 (incluse pubblicit\u00e0 \u201cinterest-based\u201d) e possono o meno avere pubblicato proprie privacy policy.<\/p>\n<p>In aggiunta, quando Lei utilizza il Sito pu\u00f2 essere indirizzato verso altri servizi che sono erogati e controllati da terze parti e che CRONDRIVE\u00a0 non controlla. Per esempio, se Lei naviga su Internet e \u201cclicca\u201d sul link presente in un sito web, il link potrebbe portarla su un diverso sito web. CRONDRIVE\u00a0 la invita a notare che quando accede a un novo sito web o applicazione e a prendere visione delle privacy policy di tutte le terze parti coinvolte e prestare attenzione in relazione ad esse. CRONDRIVE\u00a0 non \u00e8 responsabile con riferimento alla disponibilit\u00e0, completezza e accuratezza di tali privacy policy o informative di terze parti.<\/p>\n<p>&nbsp;<\/p>\n<p>LA SUA SCELTA CON RIFERIMENTO ALLA RACCOLTA DI DATI E ALLA MODIFICA DELLE PREFERENZE ESPRESSE: I SUOI DIRITI E LE SUE SCELTE<\/p>\n<p>Esattezza dei dati<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 si impegna ad attuare ogni ragionevole sforzo per assicurare che:<\/p>\n<p>\u203a i Suoi Dati Personali Trattati da CRONDRIVE\u00a0 siano esatti e, qualora necessario, tenuti aggiornati; e<\/p>\n<p>\u203a ogni e ciascun Suo Dato Personale Trattato da CRONDRIVE\u00a0 che risultasse inesatto (avuto riguardo alle finalit\u00e0 per le quali lo stesso \u00e8 Trattato) venga cancellato o modificato senza ritardo.<\/p>\n<p>Di tanto in tanto CRONDRIVE\u00a0 potr\u00e0 chiedere a Lei di confermare l\u2019esattezza dei Suoi dati Personali.<\/p>\n<p>Non eccedenza dei dati<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 si impegna ad attuare ogni ragionevole sforzo per assicurare che i Suoi dati Personali Trattati da CRONDRIVE\u00a0 siano limitati a quelli strettamente necessari in relazione alle finalit\u00e0 indicate nella presente Data Protection Policy.<\/p>\n<p>Mantenimento dei dati<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 si impegna ad attuare ogni ragionevole sforzo per assicurare che i Suoi dati Personali Trattati da CRONDRIVE\u00a0 siano Trattati per il solo periodo minimo necessario in relazione alle finalit\u00e0 indicate nella presente Data Protection Policy.<\/p>\n<p>I criteri per determinare la durata di mantenimento dei Suoi Dati Personali sono i seguenti: CRONDRIVE\u00a0 manterr\u00e0 copia dei Suoi Dati Personali in una forma che consenta l\u2019identificazione esclusivamente per il tempo necessario in relazione alle finalit\u00e0 indicate nella presente Data Protection Policy, salvo la legge applicabile richieda un periodo pi\u00f9 lungo di mantenimento degli stessi. In particolare, CRONDRIVE\u00a0 potr\u00e0 mantenere i Suoi Dati Personali per la durata necessaria a creare, esercitare o difendere un diritto di CRONDRIVE<\/p>\n<p>I Suoi diritti<\/p>\n<p>In relazione al Regolamento e alla legge applicabile, Lei potrebbe avere una serie di diritti con riferimento al Trattamento dei Suoi Dati Personali di cui CRONDRIVE\u00a0 \u00e8 Titolare, che includono:<\/p>\n<p>\u203a il diritto di non fornire a CRONDRIVE\u00a0 i Suoi Dati Personali (comunque, La preghiamo di notare che in tal caso CRONDRIVE\u00a0 pu\u00f2 non essere in grado di fornire a Lei tutti i vantaggi del Sito e delle applicazioni di cui fa richiesta);<\/p>\n<p>\u203a il diritto di richiedere l\u2019accesso ai, o copia dei, Suoi Dati Personali, unitamente alle informazioni connesse alla natura, al Trattamento, alla divulgazione di detti Dati Personali;<\/p>\n<p>\u203a il diritto di richiedere rettifiche di qualsivoglia inesattezza nei Suoi Dati Personali;<\/p>\n<p>\u203a il diritto di richiedere, su basi legittime:<\/p>\n<p>\u203a la cancellazione dei Suoi Dati Personali;<\/p>\n<p>\u203a la limitazione del Trattamento dei Suoi Dati Personali;<\/p>\n<p>\u203a il diritto di contestare, su basi legittime, il Trattamento da parte di CRONDRIVE\u00a0 o per conto di CRONDRIVE\u00a0 dei Suoi Dati Personali;<\/p>\n<p>\u203a il diritto di ottenere taluni trasferimenti di Dati Personali verso altri Titolari, in un formato strutturato, usato nella prassi e leggibile digitalmente, entro i fini applicabili;<\/p>\n<p>\u203a allorch\u00e9 CRONDRIVE\u00a0 Tratta i Suoi Dati Personali sulla base del Suo consenso, il diritto di ritirare il Suo consenso (posto che tale ritiro non inficia qualsivoglia Trattamento legittimamente effettuato prima della data in cui CRONDRIVE\u00a0 riceve notizia del ritiro stesso n\u00e9 evita il Trattamento di Suoi Dati Personali facendo affidamento su ogni altra base le- gale); e<\/p>\n<p>\u203a il diritto di presentare doglianze innanzi ad una Autorit\u00e0 Garante per la protezione dei dati personali in relazione al Trattamento da parte di CRONDRIVE\u00a0 o per conto di CRONDRIVE\u00a0 dei Suoi Dati Personali.<\/p>\n<p>Quanto sopra non pregiudica i Suoi diritti inderogabili.<\/p>\n<p>Qualora Lei volesse esercitare alcuno dei suddetti diritti, pu\u00f2 contattare CRONDRIVE\u00a0 attraverso il seguente indirizzo info@crondrive.it. Preghiamo di notare che:<\/p>\n<p>\u203a L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 potr\u00e0 richiedere prova della Sua identit\u00e0 prima di accordare efficacia ai suddetti diritti invocati; e<\/p>\n<p>\u203a qualora la Sua richiesta implicasse l\u2019accertamento di fatti ulteriori (e.g., la determinazione rispetto alla non conformit\u00e0 di taluni Trattamenti con la legge applicabile) CRONDRIVE\u00a0 valuter\u00e0 la Sua richiesta in un tempo ragionevolmente breve, prima di decidere l\u2019azione da intraprendere.<\/p>\n<p>Qualora CRONDRIVE\u00a0 ricevesse una valida richiesta di accordare efficacia a taluno dei suddetti diritti invocati, CRONDRIVE\u00a0 si impegna a ogni ragionevole sforzo entro un (1) mese ovvero, nella misura consentita dalla legge applicabile, nel minor tempo ragionevolmente consentito. Qualora Lei richiedesse la rimozione di un Suo Dato Personale, Lei riconosce che i Suoi dati Personali potranno continuare a esistere in una forma non cancellabile che sarebbe difficile o impossibile per CRONDRIVE\u00a0 localizzare, e che per motivi di archiviazione dei file, CRONDRIVE\u00a0 si riserva il diritto di mantenere ogni informazione rimossa da, o cambiata nei, database attivi per finalit\u00e0 non commerciali incluse la risoluzione delle controversie, il miglioramento del Sito(i), la risoluzione dei problemi e l\u2019applicazione della presente Data Protection Policy.<\/p>\n<p>I diritti di cui sopra non si applicano alla raccolta di Dati Non Personali.<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 si riserva il diritto di negare il Trattamento di richieste di rimozione dati che risultassero impraticabili o che pregiudicassero la privacy altrui. Il rifiuto di Trattare richieste di rimozione dati dovr\u00e0 essere giustificato dalla normativa applicabile.<\/p>\n<p>A tutti gli utilizzatori del Sito \u00e8 fatta richiesta di fornire, quando richiesto, Dati Personali veri, corretti, completi ed esatti e CRONDRIVE\u00a0 respinger\u00e0 e canceller\u00e0 ogni dato che in buona fede dovesse ritenere errato, falso, falsificato ovvero fraudolento, ovvero incoerente con, o in violazione della Data Protection Policy.<\/p>\n<p>SICUREZZA DELLE INFORMAZIONI CHE CRONDRIVE\u00a0 RACCOGLIE<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 considera con seriet\u00e0 la sicurezza dei Suoi Dati Personali. CRONDRIVE\u00a0 mantiene protezioni fisiche, amministrative e organizzative volte a preservare la riservatezza e la sicurezza dei Suoi Dati Personali. Sfortunatamente, la trasmissione di informazioni tramite Internet non \u00e8 completamente sicura. Nonostante CRONDRIVE\u00a0 fa di tutto per proteggere i Suoi Dati Personali, non pu\u00f2 essere garantire la sicurezza dei Suoi dati Personali trasmessi attraverso l\u2019utilizzo del Sito e delle applicazioni. Qualsivoglia trasmissione di Dati personale \u00e8 a Suo stesso rischio. CRONDRIVE\u00a0 non \u00e8 responsabile per l\u2019elusione di ogni e ciascuna impostazione sulla privacy o misura di sicurezza per il Sito e le applicazioni.<\/p>\n<p>BACHECHE E ALTRI SPAZI PUBBLICI<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 potr\u00e0 offrire bacheche o altre funzioni pubbliche sul Sito, e qualsivoglia Suo \u201cpost\u201d in detti spazi pubblici \u00e8 considerata informazione pubblica che \u00e8 a disposizione degli altri utenti.<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 non controlla, e non \u00e8 responsabile per, le azioni di altri utenti con riferimento a qualsivoglia informazione da Lei \u201cpostata\u201d in tali spazi. Inoltre, le informazioni che rilascia negli spazi pubblici potrebbero essere raccolti e usati da altri utenti per inviarLe messaggi non sollecitati e per finalit\u00e0 ulteriori. Ogni \u201cpost\u201d nelle bacheche e negli spazi pubblici sul Sito sono governate altres\u00ec dai termini e condizioni dei siti web di terze parti applicabili.<\/p>\n<p>Parti del Suo profilo utente possono altres\u00ec essere a disposizione di altri utenti e Lei dovr\u00e0 avere cura di non utilizzare Dati Personali nel Suo user name o in altre informazioni che potrebbero essere pubblicamente disponibili agli altri utenti.<\/p>\n<p>TRASFERIMENTO TRANSNAZIONALE DI INFORMAZIONI<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 potr\u00e0 trasferire e conservare i Dati Personali che Lei fornisce in relazione al Suo utilizzo del Sito su server situati in Paesi fuori dalla Sua giurisdizione. CRONDRIVE\u00a0 potr\u00e0 altres\u00ec trasferire Dati Personali raccolti da Lei in altri Paesi fuori dalla Sua giurisdizione a terze parti menzionate nella presente Data Protection Policy, nella misura in cui tale trasferimento risulti necessario allo scopo di adempiere alle obbligazioni di cui alla presente Data Protection Policy.<\/p>\n<p>DATA PROTECTION POLICY VERSIONI ED EMENDAMENTI<\/p>\n<p>L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 si riserva il diritto di modificare la presente Data Protection Policy in ogni momento e per qualsivoglia motivo, e pubblicher\u00e0 ogni modifica alla presente Data Protection Policy entro un tempo ragionevole dalla loro entrata in vigore. La presente Data Protection Policy rimarr\u00e0 a tutti gli effetti in vigore e avr\u00e0 piena efficacia finch\u00e9 Lei rimarr\u00e0 un utente del Sito e\/o dell\u2019Applicazione, anche qualora il Suo utilizzo del, o la Sua partecipazione a un particolare servizio, funzionalit\u00e0, funzione o attivit\u00e0 promozionale, termini, scada, cessi, venga sospesa o disattivata per qualunque ragione.<\/p>\n<p>Newsletter Informativa<\/p>\n<p>Con i seguenti avvisi, ti informiamo sui contenuti della nostra newsletter, nonch\u00e9 la procedura di registrazione, spedizione e valutazione statistica, nonch\u00e9 i tuoi diritti di opposizione. Iscrivendoti alla nostra newsletter, accetti la ricezione e le procedure descritte.<\/p>\n<p>Contenuto della newsletter: inviamo newsletter, E-mail e altre notifiche elettroniche con informazioni pubblicitarie (&#8220;newsletter&#8221;) solo con il consenso dei destinatari o un&#8217;autorizzazione legale. Se il suo contenuto \u00e8 specificatamente descritto come parte di una registrazione per la newsletter, essi sono decisivi per il consenso degli utenti. Inoltre, le nostre newsletter contengono informazioni sui nostri servizi e noi.<\/p>\n<p>Credenziali di registrazione: per iscriversi alla newsletter, \u00e8 sufficiente fornire il proprio indirizzo e-mail. Come opzione, ti chiediamo di fornire un nome per il contatto personale nella newsletter.<\/p>\n<p>Recesso\/revoca-\u00e8 possibile annullare la ricezione della nostra newsletter in qualsiasi momento, cio\u00e8 Resistete ai loro consensi. Potremmo archiviare gli indirizzi inviati via email per un massimo di tre anni sulla base dei nostri interessi legittimi prima di eliminarli per dimostrare il consenso preventivo. Il trattamento di questi dati \u00e8 limitato allo scopo di una possibile difesa contro i reclami. Una richiesta di cancellazione individuale \u00e8 possibile in qualsiasi momento, a condizione che la precedente esistenza del consenso sia confermata allo stesso tempo.<\/p>\n<p>Informazioni sulla newsletter: info@crondrive.it<\/p>\n<p>CONTATTO<\/p>\n<p>La preghiamo di voler indirizzare ogni ulteriore domanda che pu\u00f2 avere con riferimento alla presente Data Protection Policy all\u2019indirizzo email info@crondrive.it.<\/p>\n<p>&nbsp;<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;ContactForm&#8221; module_id=&#8221;contactform&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(255,255,255,0.57)&#8221; background_image=&#8221;https:\/\/fahrradtransport.it\/wp-content\/uploads\/2022\/12\/HeaderVanGrMidQua.jpg&#8221; background_blend=&#8221;lighten&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;5px||9px||false|false&#8221; global_module=&#8221;483&#8243; saved_tabs=&#8221;all&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;89%&#8221; width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;tel:+393661033444&#8243; button_text=&#8221;Hotline +39 366 10 33 444&#8243; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;44px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;gcid-e816cd01-dfac-4bab-bbcb-3f9f05e7ab9a&#8221; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;RGBA(255,255,255,0)&#8221; button_icon=&#8221;&#xf879;||fa||900&#8243; button_icon_color=&#8221;#FFFFFF&#8221; button_icon_placement=&#8221;left&#8221; button_on_hover=&#8221;off&#8221; background_layout=&#8221;dark&#8221; button_text_size_tablet=&#8221;&#8221; button_text_size_phone=&#8221;22px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{%22gcid-e816cd01-dfac-4bab-bbcb-3f9f05e7ab9a%22:%91%22button_bg_color%22%93}&#8221;][\/et_pb_button][et_pb_text _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;21px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;57px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;15px||||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;15px|1vw||1vw|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;17px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;31px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_text_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Anfrage | Richiesta | Request<\/h1>\n<p>F\u00fcr <strong>dringliche oder kurzfristige Fahrten<\/strong>, w\u00e4hlen Sie bitte unsere Hotline-Nummer.<br \/><strong>Per viaggi urgenti o di breve termine<\/strong>, si prega di chiamare il nostro numero verde.<br \/><strong>For urgent or short-notice journeys<\/strong>, please dial our hotline number.<\/p>\n<p>[\/et_pb_text][et_pb_contact_form email=&#8221;info@crondrive.it&#8221; custom_message=&#8221;Anfrage Taxiservice Website||et_pb_line_break_holder||%%Name%%||et_pb_line_break_holder||%%Email%%||et_pb_line_break_holder||%%Telefon%%||et_pb_line_break_holder||Datum: %%Pickupdate%%||et_pb_line_break_holder||Abholort: %%Abholort%%||et_pb_line_break_holder||Zielort: %%Zielort%%||et_pb_line_break_holder||Nachricht: %%Message%%||et_pb_line_break_holder||Gep\u00e4ck: %%Gepaeck%%||et_pb_line_break_holder||R\u00fcckfahrt: %%Rueckfahrt%%||et_pb_line_break_holder||||et_pb_line_break_holder||Sonstige Servicew\u00fcnsche: %%Interesse%%||et_pb_line_break_holder||||et_pb_line_break_holder||Privacy-Erkl\u00e4rung %%Privacy%%&#8221; use_redirect=&#8221;on&#8221; redirect_url=&#8221;\/bestaetigung-conferma-confirmation\/&#8221; success_message=&#8221;Vielen Dank | Grazie | Thank You&#8221; submit_button_text=&#8221;Send&#8221; module_class=&#8221;dd_icon_form&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; _unique_id=&#8221;df4ddeb8-4ad3-4edb-a5e9-a96f8a58a2b4&#8243; form_field_background_color=&#8221;#FFFFFF&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_custom_margin=&#8221;||14px||false|false&#8221; form_field_custom_padding=&#8221;|||57px|false|false&#8221; title_font=&#8221;|600|||||||&#8221; title_text_color=&#8221;#000000&#8243; title_font_size=&#8221;57px&#8221; title_letter_spacing=&#8221;3px&#8221; title_line_height=&#8221;1.5em&#8221; captcha_font=&#8221;|700|||||||&#8221; captcha_text_color=&#8221;gcid-89e93a70-3593-4e73-a02b-353099876d28&#8243; captcha_font_size=&#8221;23px&#8221; captcha_letter_spacing=&#8221;6px&#8221; captcha_line_height=&#8221;3.4em&#8221; form_field_font=&#8221;|600|||||||&#8221; form_field_font_size=&#8221;16px&#8221; form_field_line_height=&#8221;1.1em&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;25px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#999999&#8243; button_border_width=&#8221;4px&#8221; button_font=&#8221;|700|||||||&#8221; button_icon_color=&#8221;#FFFFFF&#8221; button_custom_margin=&#8221;17px||0px||false|false&#8221; button_custom_padding=&#8221;||0px||false|false&#8221; custom_margin=&#8221;12px|0px|||false|false&#8221; custom_padding=&#8221;|0px|||false|false&#8221; title_text_shadow_style=&#8221;preset1&#8243; box_shadow_style_button=&#8221;preset1&#8243; global_colors_info=&#8221;{%22gcid-89e93a70-3593-4e73-a02b-353099876d28%22:%91%22captcha_text_color%22%93}&#8221;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Name&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;E-Mail-Adresse&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.19.2&#8243; custom_margin=&#8221;|0px|0px||false|false&#8221; custom_padding=&#8221;|0px|0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Telefon&#8221; field_title=&#8221;Telefon&#8221; _builder_version=&#8221;4.19.2&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;pickupdate&#8221; field_title=&#8221;Abholdatum | Data di ritiro | Pick up date&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Abholort&#8221; field_title=&#8221;Abholort | partenza | pickup location  &#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Zielort&#8221; field_title=&#8221;Ziel | arrivo | drop-off-location&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Rueckfahrt&#8221; field_title=&#8221;R\u00fcckfahrt | Ritorno | Return&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22Ja%22,%22checked%22:0,%22dragID%22:-1},{%22value%22:%22Nein%22,%22checked%22:0,%22dragID%22:0}%93&#8243; required_mark=&#8221;off&#8221; _builder_version=&#8221;4.19.2&#8243; form_field_background_color=&#8221;#FFFFFF&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_focus_background_color=&#8221;#FFFFFF&#8221; form_field_focus_text_color=&#8221;#000000&#8243; form_field_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Gepaeck&#8221; field_title=&#8221;Gep\u00e4ck | Bagaglio | Luggage&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22Ja%22,%22checked%22:0,%22dragID%22:-1},{%22value%22:%22Nein%22,%22checked%22:0,%22dragID%22:0}%93&#8243; required_mark=&#8221;off&#8221; _builder_version=&#8221;4.19.2&#8243; form_field_background_color=&#8221;#FFFFFF&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_focus_background_color=&#8221;#FFFFFF&#8221; form_field_focus_text_color=&#8221;#000000&#8243; form_field_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Message&#8221; field_title=&#8221;Nachricht | messaggio | message&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Interesse&#8221; field_title=&#8221;Service&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22Taxiservice%22,%22checked%22:0,%22dragID%22:-1},{%22value%22:%22Shuttle%22,%22checked%22:0,%22dragID%22:0},{%22dragID%22:1,%22value%22:%22Airport-Transfer%22,%22checked%22:0},{%22value%22:%22Hotelservice%22,%22checked%22:0,%22dragID%22:2},{%22value%22:%22Concerts\/Party\/Event%22,%22checked%22:0,%22dragID%22:3},{%22dragID%22:4,%22value%22:%22Biketransport%22,%22checked%22:0},{%22dragID%22:5,%22value%22:%22Paraglider%22,%22checked%22:0},{%22dragID%22:7,%22value%22:%22Kindersitz | seggiolino per bambini | child seat%22,%22checked%22:0},{%22value%22:%22Anderes | Altro | Other %22,%22checked%22:0,%22dragID%22:6}%93&#8243; required_mark=&#8221;off&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_focus_text_color=&#8221;#000000&#8243; form_field_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Privacy&#8221; field_title=&#8221;  Datenschutz | Privacy&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22Ich erkl\u00e4re mich mit der Datenschutzerkl\u00e4rung von CronDrive einverstanden (Pflichtfeld)%22,%22checked%22:0,%22dragID%22:-1,%22link_url%22:%22\/privacy\/%22}%93&#8243; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Privacy &#8211; Cookies Informativa sulla protezione della privacy Responsabile ai sensi del regolamento sulla protezione dei dati personali Nello specifico, Le forniamo le seguenti informazioni: L\u00b4 impresa CronDrive Brunico utilizzer\u00e0 i Vostri dati per i seguenti scopi: \u203a invio di email e comunicazioni; \u203a comunicazioni con Lei; \u203a comunicazioni e operazioni IT; \u203a gestione finanziaria; \u203a fornire a Lei materiale promozionale a Sua richiesta; \u203a procedimenti legali: creazione, esercizio e difesa di diritti; \u203a adeguamento alla legge applicabile; \u203a miglioramento del sito; \u203a adempiere a eventuali obblighi contrattuali nei confronti dell\u2019interessato, alla tutela del credito e gestione del debito. \u203a registrazione del Suo account; L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 garantisce ai sensi della Normativa Privacy Applicabile che il trattamento dei dati personali avviene nel rispetto dei diritti fondamentali nonch\u00e9 della dignit\u00e0 dell\u2019interessato, in particolare per quanto riguarda la segretezza, l\u2019identit\u00e0 personale, il diritto alla tutela degli stessi, nonch\u00e9 alla loro cancellazione su richiesta dell\u2019interessato. In relazione alle finalit\u00e0 di cui sopra, i Vostri dati personali saranno comunicati se necessario: \u203a alle Pubbliche Amministrazioni e Autorit\u00e0, ove previsto dalla legge e dalla Normativa Privacy Applicabile; \u203a a Istituti di credito con i quali la nostra societ\u00e0 ha rapporti per la gestione dei [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1264","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Privacy - CronDrive Bike-Taxi.it NCC Bruneck Brunico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fahrradtransport.it\/it\/privacy\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Privacy - CronDrive Bike-Taxi.it NCC Bruneck Brunico\" \/>\n<meta property=\"og:description\" content=\"Privacy - Cookies Informativa sulla protezione della privacy Responsabile ai sensi del regolamento sulla protezione dei dati personali Nello specifico, Le forniamo le seguenti informazioni: L\u00b4 impresa CronDrive Brunico utilizzer\u00e0 i Vostri dati per i seguenti scopi: \u203a invio di email e comunicazioni; \u203a comunicazioni con Lei; \u203a comunicazioni e operazioni IT; \u203a gestione finanziaria; \u203a fornire a Lei materiale promozionale a Sua richiesta; \u203a procedimenti legali: creazione, esercizio e difesa di diritti; \u203a adeguamento alla legge applicabile; \u203a miglioramento del sito; \u203a adempiere a eventuali obblighi contrattuali nei confronti dell\u2019interessato, alla tutela del credito e gestione del debito. \u203a registrazione del Suo account; L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 garantisce ai sensi della Normativa Privacy Applicabile che il trattamento dei dati personali avviene nel rispetto dei diritti fondamentali nonch\u00e9 della dignit\u00e0 dell\u2019interessato, in particolare per quanto riguarda la segretezza, l\u2019identit\u00e0 personale, il diritto alla tutela degli stessi, nonch\u00e9 alla loro cancellazione su richiesta dell\u2019interessato. In relazione alle finalit\u00e0 di cui sopra, i Vostri dati personali saranno comunicati se necessario: \u203a alle Pubbliche Amministrazioni e Autorit\u00e0, ove previsto dalla legge e dalla Normativa Privacy Applicabile; \u203a a Istituti di credito con i quali la nostra societ\u00e0 ha rapporti per la gestione dei [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fahrradtransport.it\/it\/privacy\/\" \/>\n<meta property=\"og:site_name\" content=\"CronDrive Bike-Taxi.it NCC Bruneck Brunico\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T18:31:52+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"46 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/privacy\\\/\",\"url\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/privacy\\\/\",\"name\":\"Privacy - CronDrive Bike-Taxi.it NCC Bruneck Brunico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/#website\"},\"datePublished\":\"2022-12-08T17:11:02+00:00\",\"dateModified\":\"2023-06-14T18:31:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/privacy\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/privacy\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/privacy\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privacy\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/\",\"name\":\"CronDrive Bike-Taxi.it NCC Bruneck Brunico\",\"description\":\"Biketransport Taxiservice N.C.C.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Privacy - CronDrive Bike-Taxi.it NCC Bruneck Brunico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fahrradtransport.it\/it\/privacy\/","og_locale":"it_IT","og_type":"article","og_title":"Privacy - CronDrive Bike-Taxi.it NCC Bruneck Brunico","og_description":"Privacy - Cookies Informativa sulla protezione della privacy Responsabile ai sensi del regolamento sulla protezione dei dati personali Nello specifico, Le forniamo le seguenti informazioni: L\u00b4 impresa CronDrive Brunico utilizzer\u00e0 i Vostri dati per i seguenti scopi: \u203a invio di email e comunicazioni; \u203a comunicazioni con Lei; \u203a comunicazioni e operazioni IT; \u203a gestione finanziaria; \u203a fornire a Lei materiale promozionale a Sua richiesta; \u203a procedimenti legali: creazione, esercizio e difesa di diritti; \u203a adeguamento alla legge applicabile; \u203a miglioramento del sito; \u203a adempiere a eventuali obblighi contrattuali nei confronti dell\u2019interessato, alla tutela del credito e gestione del debito. \u203a registrazione del Suo account; L\u00b4 IMPRESA CRONDRIVE BRUNICO\u00a0 garantisce ai sensi della Normativa Privacy Applicabile che il trattamento dei dati personali avviene nel rispetto dei diritti fondamentali nonch\u00e9 della dignit\u00e0 dell\u2019interessato, in particolare per quanto riguarda la segretezza, l\u2019identit\u00e0 personale, il diritto alla tutela degli stessi, nonch\u00e9 alla loro cancellazione su richiesta dell\u2019interessato. In relazione alle finalit\u00e0 di cui sopra, i Vostri dati personali saranno comunicati se necessario: \u203a alle Pubbliche Amministrazioni e Autorit\u00e0, ove previsto dalla legge e dalla Normativa Privacy Applicabile; \u203a a Istituti di credito con i quali la nostra societ\u00e0 ha rapporti per la gestione dei [&hellip;]","og_url":"https:\/\/fahrradtransport.it\/it\/privacy\/","og_site_name":"CronDrive Bike-Taxi.it NCC Bruneck Brunico","article_modified_time":"2023-06-14T18:31:52+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"46 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fahrradtransport.it\/it\/privacy\/","url":"https:\/\/fahrradtransport.it\/it\/privacy\/","name":"Privacy - CronDrive Bike-Taxi.it NCC Bruneck Brunico","isPartOf":{"@id":"https:\/\/fahrradtransport.it\/it\/#website"},"datePublished":"2022-12-08T17:11:02+00:00","dateModified":"2023-06-14T18:31:52+00:00","breadcrumb":{"@id":"https:\/\/fahrradtransport.it\/it\/privacy\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fahrradtransport.it\/it\/privacy\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fahrradtransport.it\/it\/privacy\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/fahrradtransport.it\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Privacy"}]},{"@type":"WebSite","@id":"https:\/\/fahrradtransport.it\/it\/#website","url":"https:\/\/fahrradtransport.it\/it\/","name":"CronDrive Bike-Taxi.it NCC Bruneck Brunico","description":"Biketransport Taxiservice N.C.C.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fahrradtransport.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 14:59:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/pages\/1264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/comments?post=1264"}],"version-history":[{"count":2,"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/pages\/1264\/revisions"}],"predecessor-version":[{"id":1276,"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/pages\/1264\/revisions\/1276"}],"wp:attachment":[{"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/media?parent=1264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}