{"id":1284,"date":"2022-12-08T17:58:41","date_gmt":"2022-12-08T16:58:41","guid":{"rendered":"https:\/\/bike-taxi.it\/impressum\/"},"modified":"2023-06-14T21:47:41","modified_gmt":"2023-06-14T19:47:41","slug":"impressum","status":"publish","type":"page","link":"https:\/\/fahrradtransport.it\/it\/impressum\/","title":{"rendered":"Impressum"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; disabled_on=&#8221;on|on|off&#8221; admin_label=&#8221;MainMenu&#8221; _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#000000&#8243; custom_padding=&#8221;2vh||29px||false|false&#8221; global_colors_info=&#8221;{}&#8221; global_module=&#8221;1070&#8243; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.20.2&#8243; _module_preset=&#8221;default&#8221; parallax=&#8221;on&#8221; width=&#8221;82%&#8221; max_width=&#8221;100%&#8221; module_alignment=&#8221;center&#8221; custom_margin=&#8221;||-6px||false|false&#8221; custom_padding=&#8221;0px||0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.18.0&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_menu db_title_and_tagline_valign=&#8221;bottom&#8221; active_link_color=&#8221;rgba(255,255,255,0.55)&#8221; dropdown_menu_bg_color=&#8221;#7a7a7a&#8221; dropdown_menu_line_color=&#8221;#FFFFFF&#8221; logo=&#8221;https:\/\/fahrradtransport.it\/wp-content\/uploads\/2023\/04\/CronDriveBikeTransportWhiteTransp3.png&#8221; logo_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoiaG9tZV91cmwiLCJzZXR0aW5ncyI6e319@&#8221; logo_max_width=&#8221;35%&#8221; show_search_icon=&#8221;on&#8221; search_icon_color=&#8221;#FFFFFF&#8221; menu_icon_color=&#8221;#FFFFFF&#8221; _builder_version=&#8221;4.20.2&#8243; _dynamic_attributes=&#8221;logo_url&#8221; _module_preset=&#8221;default&#8221; menu_font=&#8221;|600|||||||&#8221; menu_text_color=&#8221;#FFFFFF&#8221; menu_font_size=&#8221;22px&#8221; menu_line_height=&#8221;1.1em&#8221; db_tagline_text_align=&#8221;left&#8221; db_tagline_text_color=&#8221;#FFFFFF&#8221; db_tagline_font_size=&#8221;20px&#8221; db_tagline_line_height=&#8221;1.6em&#8221; background_enable_color=&#8221;off&#8221; background_layout=&#8221;dark&#8221; custom_padding=&#8221;8px|2px|11px|0px|false|false&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][\/et_pb_menu][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;HeaderBild&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_stops=&#8221;rgba(252,164,50,0.09) 0%|rgba(183,30,0,0.14) 100%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_image=&#8221;https:\/\/fahrradtransport.it\/wp-content\/uploads\/2022\/12\/HeaderVanGrMidQua.jpg&#8221; parallax=&#8221;on&#8221; parallax_method=&#8221;off&#8221; custom_padding=&#8221;12vh||11vh||false|false&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row padding_top_bottom_link_2=&#8221;true&#8221; padding_left_right_link_2=&#8221;true&#8221; _builder_version=&#8221;4.19.2&#8243; background_color=&#8221;rgba(255,255,255,0.91)&#8221; custom_padding=&#8221;|30px||30px|false|true&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.19.2&#8243; text_font=&#8221;||||||||&#8221; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_font_size=&#8221;33px&#8221; header_line_height=&#8221;1.4em&#8221; header_2_text_align=&#8221;center&#8221; header_4_font=&#8221;|700||on|||||&#8221; header_4_text_align=&#8221;center&#8221; header_4_text_color=&#8221;rgba(0,0,0,0.5)&#8221; header_4_font_size=&#8221;14px&#8221; header_4_letter_spacing=&#8221;1px&#8221; header_4_line_height=&#8221;1.5em&#8221; custom_margin=&#8221;||6px|||&#8221; custom_padding=&#8221;||0px|||&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Impressum &#8211; Imprint<\/h1>\n<h2>Responsabile del contenuto<\/h2>\n<h4><\/h4>\n<p>[\/et_pb_text][et_pb_blurb title=&#8221;Roland Niederkofler &#8211; Cron Drive&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;\uf1ea||fa||400&#8243; icon_color=&#8221;#293600&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;20px&#8221; _builder_version=&#8221;4.19.2&#8243; header_font=&#8221;Raleway|700|||||||&#8221; header_text_color=&#8221;#1d2600&#8243; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;20px||5px|||&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;+39 366 10 33 444&#8243; use_icon=&#8221;on&#8221; font_icon=&#8221;\ue090||divi||400&#8243; icon_color=&#8221;#293600&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;20px&#8221; _builder_version=&#8221;4.19.2&#8243; header_font=&#8221;Raleway|700||on|||||&#8221; header_text_color=&#8221;#1d2600&#8243; header_font_size=&#8221;19px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; body_font_size=&#8221;18px&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;3px||14px|||&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;info@crondrive.it&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;\ue076||divi||400&#8243; icon_color=&#8221;#293600&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;20px&#8221; _builder_version=&#8221;4.19.2&#8243; header_font=&#8221;Raleway|700|||||||&#8221; header_text_color=&#8221;#1d2600&#8243; header_font_size=&#8221;18px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;20px||13px|||&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;Bruneck | Brunico S\u00fcdtirol | South Tyrol | Alto Adige&#8221; use_icon=&#8221;on&#8221; font_icon=&#8221;\ue081||divi||400&#8243; icon_color=&#8221;#293600&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;20px&#8221; _builder_version=&#8221;4.19.2&#8243; header_font=&#8221;Raleway|700|||||||&#8221; header_text_color=&#8221;#1d2600&#8243; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;20px|||&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_blurb title=&#8221;MWSTR. | PART.IVA | VAT: IT03168740219&#8243; icon_placement=&#8221;left&#8221; image_icon_width=&#8221;20px&#8221; _builder_version=&#8221;4.19.2&#8243; header_font=&#8221;Raleway|700|||||||&#8221; header_text_color=&#8221;#1d2600&#8243; header_font_size=&#8221;16px&#8221; header_letter_spacing=&#8221;2px&#8221; header_line_height=&#8221;1.8em&#8221; background_layout=&#8221;dark&#8221; custom_margin=&#8221;20px|||&#8221; animation=&#8221;off&#8221; icon_font_size=&#8221;20px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_blurb][et_pb_text _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h2><strong>Condizioni di utilizzo del sito web<\/strong><\/h2>\n<p>Le foto o i video utilizzati in questo sito web provengono da archivi online e da<\/p>\n<p>Foto: Barbara Sitzmann Wieser<br \/>Foto: Archivi online &#8211; Archivi propri<\/p>\n<p><strong>Utilizzando questo sito web, l&#8217;utente accetta i seguenti termini e condizioni:<\/strong><\/p>\n<p>Il contenuto di questo sito web (dati, immagini, grafici, foto, testi) &#8211; ad eccezione dei marchi di terzi &#8211; \u00e8 di propriet\u00e0 di Cron Drive ed \u00e8 protetto da copyright.<br \/>I diritti d&#8217;autore delle foto dei fotografi professionisti appartengono ai rispettivi fotografi. Tutti i diritti riservati. La riproduzione, la modifica, la distribuzione e qualsiasi tipo di sfruttamento al di fuori dei limiti del copyright richiedono il nostro consenso scritto.<\/p>\n<p>Le informazioni contenute in questo sito web sono soggette a modifiche senza preavviso. Le informazioni contenute in questo sito web sono soggette a modifiche senza preavviso.<\/p>\n<h4><strong>Marchi di terzi<\/strong><\/h4>\n<p>I marchi e i nomi dei marchi di terzi sono di loro propriet\u00e0 e quindi protetti dal diritto d&#8217;autore.<\/p>\n<p>Sono riprodotti in questa pagina al solo scopo di fornire informazioni complete.<\/p>\n<h4><strong>Link esterni<\/strong><\/h4>\n<p>Nonostante l&#8217;attento controllo dei contenuti, non ci assumiamo alcuna responsabilit\u00e0 per il contenuto dei link esterni. I gestori delle pagine collegate sono gli unici responsabili del loro contenuto.<\/p>\n<h4><strong>Diritto e giurisdizione<\/strong><\/h4>\n<p>La sede legale per eventuali controversie legali \u00e8 Bolzano, Alto Adige, Italia<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][et_pb_row _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;#contactform&#8221; button_text=&#8221;Bestellen Sie ein Taxi&#8221; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;29px&#8221; button_bg_color=&#8221;gcid-e816cd01-dfac-4bab-bbcb-3f9f05e7ab9a&#8221; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{%22gcid-e816cd01-dfac-4bab-bbcb-3f9f05e7ab9a%22:%91%22button_bg_color%22%93}&#8221;][\/et_pb_button][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;on|phone&#8221; admin_label=&#8221;ContactForm&#8221; module_id=&#8221;contactform&#8221; _builder_version=&#8221;4.20.4&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;rgba(255,255,255,0.81)&#8221; background_image=&#8221;https:\/\/fahrradtransport.it\/wp-content\/uploads\/2023\/04\/anhaenger.jpg&#8221; background_blend=&#8221;lighten&#8221; custom_padding_phone=&#8221;5px||9px||false|false&#8221; global_module=&#8221;483&#8243; saved_tabs=&#8221;all&#8221; collapsed=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; width_tablet=&#8221;&#8221; width_phone=&#8221;89%&#8221; width_last_edited=&#8221;on|phone&#8221; module_alignment=&#8221;center&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_button button_url=&#8221;tel:+393661033444&#8243; button_text=&#8221;Hotline +39 366 10 33 444&#8243; button_alignment=&#8221;center&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;44px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;gcid-e816cd01-dfac-4bab-bbcb-3f9f05e7ab9a&#8221; button_border_width=&#8221;0px&#8221; button_border_color=&#8221;RGBA(255,255,255,0)&#8221; button_icon=&#8221;\uf879||fa||900&#8243; button_icon_color=&#8221;#FFFFFF&#8221; button_icon_placement=&#8221;left&#8221; button_on_hover=&#8221;off&#8221; background_layout=&#8221;dark&#8221; button_text_size_tablet=&#8221;&#8221; button_text_size_phone=&#8221;22px&#8221; button_text_size_last_edited=&#8221;on|phone&#8221; global_colors_info=&#8221;{%22gcid-e816cd01-dfac-4bab-bbcb-3f9f05e7ab9a%22:%91%22button_bg_color%22%93}&#8221;][\/et_pb_button][et_pb_text _builder_version=&#8221;4.19.4&#8243; _module_preset=&#8221;default&#8221; text_font_size=&#8221;21px&#8221; text_line_height=&#8221;1.8em&#8221; header_font=&#8221;|700|||||||&#8221; header_text_align=&#8221;center&#8221; header_text_color=&#8221;#000000&#8243; header_font_size=&#8221;57px&#8221; header_line_height=&#8221;1.2em&#8221; text_orientation=&#8221;center&#8221; custom_padding=&#8221;15px||||false|false&#8221; custom_padding_tablet=&#8221;&#8221; custom_padding_phone=&#8221;15px|1vw||1vw|false|true&#8221; custom_padding_last_edited=&#8221;on|phone&#8221; text_font_size_tablet=&#8221;&#8221; text_font_size_phone=&#8221;17px&#8221; text_font_size_last_edited=&#8221;on|phone&#8221; header_font_size_tablet=&#8221;&#8221; header_font_size_phone=&#8221;31px&#8221; header_font_size_last_edited=&#8221;on|phone&#8221; header_text_shadow_style=&#8221;preset1&#8243; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h1>Anfrage | Richiesta | Request<\/h1>\n<p>F\u00fcr <strong>dringliche oder kurzfristige Fahrten<\/strong>, w\u00e4hlen Sie bitte unsere Hotline-Nummer.<br \/><strong>Per viaggi urgenti o di breve termine<\/strong>, si prega di chiamare il nostro numero verde.<br \/><strong>For urgent or short-notice rides<\/strong>, please dial our hotline number.<\/p>\n<p>[\/et_pb_text][et_pb_contact_form use_spam_service=&#8221;on&#8221; recaptcha_list=&#8221;Bike-Taxiit-0&#8243; email=&#8221;info@bike-taxi.it&#8221; custom_message=&#8221;Anfrage Taxiservice Website||et_pb_line_break_holder||%%Name%%||et_pb_line_break_holder||%%Email%%||et_pb_line_break_holder||%%Telefon%%||et_pb_line_break_holder||Datum: %%Pickupdate%%||et_pb_line_break_holder||Abholort: %%Abholort%%||et_pb_line_break_holder||Zielort: %%Zielort%%||et_pb_line_break_holder||Nachricht: %%Message%%||et_pb_line_break_holder||Gep\u00e4ck: %%Gepaeck%%||et_pb_line_break_holder||R\u00fcckfahrt: %%Rueckfahrt%%||et_pb_line_break_holder||Sportger\u00e4te: %%sportgeraete%%||et_pb_line_break_holder||Zahl der Personen: %%zahl%%||et_pb_line_break_holder||Privacy-Erkl\u00e4rung %%Privacy%%&#8221; use_redirect=&#8221;on&#8221; redirect_url=&#8221;\/bestaetigung-conferma-confirmation\/&#8221; success_message=&#8221;Vielen Dank | Grazie | Thank You&#8221; submit_button_text=&#8221;Send&#8221; module_class=&#8221;dd_icon_form&#8221; _builder_version=&#8221;4.20.4&#8243; _module_preset=&#8221;default&#8221; _unique_id=&#8221;df4ddeb8-4ad3-4edb-a5e9-a96f8a58a2b4&#8243; form_field_background_color=&#8221;#FFFFFF&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_custom_margin=&#8221;||14px||false|false&#8221; form_field_custom_padding=&#8221;|||57px|false|false&#8221; title_font=&#8221;|600|||||||&#8221; title_text_color=&#8221;#000000&#8243; title_font_size=&#8221;57px&#8221; title_letter_spacing=&#8221;3px&#8221; title_line_height=&#8221;1.5em&#8221; captcha_font=&#8221;|700|||||||&#8221; captcha_text_color=&#8221;gcid-89e93a70-3593-4e73-a02b-353099876d28&#8243; captcha_font_size=&#8221;23px&#8221; captcha_letter_spacing=&#8221;6px&#8221; captcha_line_height=&#8221;3.4em&#8221; form_field_font=&#8221;|600|||||||&#8221; form_field_font_size=&#8221;16px&#8221; form_field_line_height=&#8221;1.1em&#8221; custom_button=&#8221;on&#8221; button_text_size=&#8221;25px&#8221; button_text_color=&#8221;#FFFFFF&#8221; button_bg_color=&#8221;#999999&#8243; button_border_width=&#8221;4px&#8221; button_font=&#8221;|700|||||||&#8221; button_icon_color=&#8221;#FFFFFF&#8221; button_custom_margin=&#8221;17px||0px||false|false&#8221; button_custom_padding=&#8221;||0px||false|false&#8221; custom_margin=&#8221;12px|0px|||false|false&#8221; custom_padding=&#8221;|0px|||false|false&#8221; title_text_shadow_style=&#8221;preset1&#8243; box_shadow_style_button=&#8221;preset1&#8243; global_colors_info=&#8221;{%22gcid-89e93a70-3593-4e73-a02b-353099876d28%22:%91%22captcha_text_color%22%93}&#8221;][et_pb_contact_field field_id=&#8221;Name&#8221; field_title=&#8221;Name&#8221; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Email&#8221; field_title=&#8221;E-Mail-Adresse&#8221; field_type=&#8221;email&#8221; _builder_version=&#8221;4.19.2&#8243; custom_margin=&#8221;|0px|0px||false|false&#8221; custom_padding=&#8221;|0px|0px||false|false&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Telefon&#8221; field_title=&#8221;Telefon&#8221; _builder_version=&#8221;4.19.2&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;pickupdate&#8221; field_title=&#8221;Abholdatum | Data di ritiro | Pick up date&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Abholort&#8221; field_title=&#8221;Abholort | partenza | pickup location  &#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Zielort&#8221; field_title=&#8221;Ziel | arrivo | drop-off-location&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Rueckfahrt&#8221; field_title=&#8221;R\u00fcckfahrt | Ritorno | Return&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22Ja%22,%22checked%22:0,%22dragID%22:-1},{%22value%22:%22Nein%22,%22checked%22:0,%22dragID%22:0}%93&#8243; required_mark=&#8221;off&#8221; _builder_version=&#8221;4.19.2&#8243; form_field_background_color=&#8221;#FFFFFF&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_focus_background_color=&#8221;#FFFFFF&#8221; form_field_focus_text_color=&#8221;#000000&#8243; form_field_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Gepaeck&#8221; field_title=&#8221;Gep\u00e4ck | Bagaglio | Luggage&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22Ja%22,%22checked%22:0,%22dragID%22:-1},{%22value%22:%22Nein%22,%22checked%22:0,%22dragID%22:0}%93&#8243; required_mark=&#8221;off&#8221; _builder_version=&#8221;4.20.4&#8243; form_field_background_color=&#8221;#FFFFFF&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_focus_background_color=&#8221;#FFFFFF&#8221; form_field_focus_text_color=&#8221;#000000&#8243; form_field_font_size=&#8221;17px&#8221; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Message&#8221; field_title=&#8221;Nachricht | messaggio | message&#8221; field_type=&#8221;text&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; global_colors_info=&#8221;{}&#8221; button_text_size__hover_enabled=&#8221;off&#8221; button_one_text_size__hover_enabled=&#8221;off&#8221; button_two_text_size__hover_enabled=&#8221;off&#8221; button_text_color__hover_enabled=&#8221;off&#8221; button_one_text_color__hover_enabled=&#8221;off&#8221; button_two_text_color__hover_enabled=&#8221;off&#8221; button_border_width__hover_enabled=&#8221;off&#8221; button_one_border_width__hover_enabled=&#8221;off&#8221; button_two_border_width__hover_enabled=&#8221;off&#8221; button_border_color__hover_enabled=&#8221;off&#8221; button_one_border_color__hover_enabled=&#8221;off&#8221; button_two_border_color__hover_enabled=&#8221;off&#8221; button_border_radius__hover_enabled=&#8221;off&#8221; button_one_border_radius__hover_enabled=&#8221;off&#8221; button_two_border_radius__hover_enabled=&#8221;off&#8221; button_letter_spacing__hover_enabled=&#8221;off&#8221; button_one_letter_spacing__hover_enabled=&#8221;off&#8221; button_two_letter_spacing__hover_enabled=&#8221;off&#8221; button_bg_color__hover_enabled=&#8221;off&#8221; button_one_bg_color__hover_enabled=&#8221;off&#8221; button_two_bg_color__hover_enabled=&#8221;off&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Sportgeraete&#8221; field_title=&#8221;Sportgeraete&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22Fahrr\u00e4der | Bici | Bikes%22,%22checked%22:0,%22dragID%22:-1},{%22value%22:%22E-Bikes%22,%22checked%22:0,%22dragID%22:0},{%22dragID%22:1,%22value%22:%22Paraglider%22,%22checked%22:0},{%22value%22:%22Ski%22,%22checked%22:0,%22dragID%22:2},{%22value%22:%22Outdoor &amp; Mountain%22,%22checked%22:0,%22dragID%22:3},{%22dragID%22:4,%22value%22:%22Diving%22,%22checked%22:0},{%22dragID%22:6,%22value%22:%22Kindersitz | seggiolino per bambini | child seat%22,%22checked%22:0},{%22value%22:%22Anderes | Altro | Other %22,%22checked%22:0,%22dragID%22:7}%93&#8243; required_mark=&#8221;off&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.20.4&#8243; _module_preset=&#8221;default&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_focus_text_color=&#8221;#000000&#8243; form_field_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Zahl&#8221; field_title=&#8221;Zahl der Personen&#8221; field_type=&#8221;select&#8221; select_options=&#8221;%91{%22value%22:%221%22,%22checked%22:0,%22dragID%22:-1},{%22value%22:%222%22,%22checked%22:0,%22dragID%22:0},{%22value%22:%223%22,%22checked%22:0,%22dragID%22:1},{%22value%22:%224%22,%22checked%22:0,%22dragID%22:2},{%22value%22:%225%22,%22checked%22:0,%22dragID%22:3},{%22value%22:%226%22,%22checked%22:0,%22dragID%22:4},{%22value%22:%227%22,%22checked%22:0,%22dragID%22:5},{%22value%22:%228%22,%22checked%22:0,%22dragID%22:6},{%22value%22:%228+%22,%22checked%22:0,%22dragID%22:7}%93&#8243; required_mark=&#8221;off&#8221; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.20.4&#8243; _module_preset=&#8221;default&#8221; form_field_text_color=&#8221;#000000&#8243; form_field_focus_text_color=&#8221;#000000&#8243; form_field_font_size=&#8221;18px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][et_pb_contact_field field_id=&#8221;Privacy&#8221; field_title=&#8221;  Datenschutz | Privacy&#8221; field_type=&#8221;checkbox&#8221; checkbox_options=&#8221;%91{%22value%22:%22Ich erkl\u00e4re mich mit der Datenschutzerkl\u00e4rung von CronDrive einverstanden (Pflichtfeld)%22,%22checked%22:0,%22dragID%22:-1,%22link_url%22:%22\/privacy\/%22}%93&#8243; fullwidth_field=&#8221;on&#8221; _builder_version=&#8221;4.19.2&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_contact_field][\/et_pb_contact_form][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Impressum &#8211; Imprint Responsabile del contenuto Condizioni di utilizzo del sito web Le foto o i video utilizzati in questo sito web provengono da archivi online e da Foto: Barbara Sitzmann WieserFoto: Archivi online &#8211; Archivi propri Utilizzando questo sito web, l&#8217;utente accetta i seguenti termini e condizioni: Il contenuto di questo sito web (dati, immagini, grafici, foto, testi) &#8211; ad eccezione dei marchi di terzi &#8211; \u00e8 di propriet\u00e0 di Cron Drive ed \u00e8 protetto da copyright.I diritti d&#8217;autore delle foto dei fotografi professionisti appartengono ai rispettivi fotografi. Tutti i diritti riservati. La riproduzione, la modifica, la distribuzione e qualsiasi tipo di sfruttamento al di fuori dei limiti del copyright richiedono il nostro consenso scritto. Le informazioni contenute in questo sito web sono soggette a modifiche senza preavviso. Le informazioni contenute in questo sito web sono soggette a modifiche senza preavviso. Marchi di terzi I marchi e i nomi dei marchi di terzi sono di loro propriet\u00e0 e quindi protetti dal diritto d&#8217;autore. Sono riprodotti in questa pagina al solo scopo di fornire informazioni complete. Link esterni Nonostante l&#8217;attento controllo dei contenuti, non ci assumiamo alcuna responsabilit\u00e0 per il contenuto dei link esterni. I gestori delle pagine collegate sono [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"class_list":["post-1284","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Impressum - CronDrive Bike-Taxi.it NCC Bruneck Brunico<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/fahrradtransport.it\/it\/impressum\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Impressum - CronDrive Bike-Taxi.it NCC Bruneck Brunico\" \/>\n<meta property=\"og:description\" content=\"Impressum - Imprint Responsabile del contenuto Condizioni di utilizzo del sito web Le foto o i video utilizzati in questo sito web provengono da archivi online e da Foto: Barbara Sitzmann WieserFoto: Archivi online - Archivi propri Utilizzando questo sito web, l&#039;utente accetta i seguenti termini e condizioni: Il contenuto di questo sito web (dati, immagini, grafici, foto, testi) - ad eccezione dei marchi di terzi - \u00e8 di propriet\u00e0 di Cron Drive ed \u00e8 protetto da copyright.I diritti d&#039;autore delle foto dei fotografi professionisti appartengono ai rispettivi fotografi. Tutti i diritti riservati. La riproduzione, la modifica, la distribuzione e qualsiasi tipo di sfruttamento al di fuori dei limiti del copyright richiedono il nostro consenso scritto. Le informazioni contenute in questo sito web sono soggette a modifiche senza preavviso. Le informazioni contenute in questo sito web sono soggette a modifiche senza preavviso. Marchi di terzi I marchi e i nomi dei marchi di terzi sono di loro propriet\u00e0 e quindi protetti dal diritto d&#039;autore. Sono riprodotti in questa pagina al solo scopo di fornire informazioni complete. Link esterni Nonostante l&#039;attento controllo dei contenuti, non ci assumiamo alcuna responsabilit\u00e0 per il contenuto dei link esterni. I gestori delle pagine collegate sono [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/fahrradtransport.it\/it\/impressum\/\" \/>\n<meta property=\"og:site_name\" content=\"CronDrive Bike-Taxi.it NCC Bruneck Brunico\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-14T19:47:41+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"15 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/impressum\\\/\",\"url\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/impressum\\\/\",\"name\":\"Impressum - CronDrive Bike-Taxi.it NCC Bruneck Brunico\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/#website\"},\"datePublished\":\"2022-12-08T16:58:41+00:00\",\"dateModified\":\"2023-06-14T19:47:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/impressum\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/impressum\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/impressum\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Impressum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/\",\"name\":\"CronDrive Bike-Taxi.it NCC Bruneck Brunico\",\"description\":\"Biketransport Taxiservice N.C.C.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/fahrradtransport.it\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Impressum - CronDrive Bike-Taxi.it NCC Bruneck Brunico","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/fahrradtransport.it\/it\/impressum\/","og_locale":"it_IT","og_type":"article","og_title":"Impressum - CronDrive Bike-Taxi.it NCC Bruneck Brunico","og_description":"Impressum - Imprint Responsabile del contenuto Condizioni di utilizzo del sito web Le foto o i video utilizzati in questo sito web provengono da archivi online e da Foto: Barbara Sitzmann WieserFoto: Archivi online - Archivi propri Utilizzando questo sito web, l'utente accetta i seguenti termini e condizioni: Il contenuto di questo sito web (dati, immagini, grafici, foto, testi) - ad eccezione dei marchi di terzi - \u00e8 di propriet\u00e0 di Cron Drive ed \u00e8 protetto da copyright.I diritti d'autore delle foto dei fotografi professionisti appartengono ai rispettivi fotografi. Tutti i diritti riservati. La riproduzione, la modifica, la distribuzione e qualsiasi tipo di sfruttamento al di fuori dei limiti del copyright richiedono il nostro consenso scritto. Le informazioni contenute in questo sito web sono soggette a modifiche senza preavviso. Le informazioni contenute in questo sito web sono soggette a modifiche senza preavviso. Marchi di terzi I marchi e i nomi dei marchi di terzi sono di loro propriet\u00e0 e quindi protetti dal diritto d'autore. Sono riprodotti in questa pagina al solo scopo di fornire informazioni complete. Link esterni Nonostante l'attento controllo dei contenuti, non ci assumiamo alcuna responsabilit\u00e0 per il contenuto dei link esterni. I gestori delle pagine collegate sono [&hellip;]","og_url":"https:\/\/fahrradtransport.it\/it\/impressum\/","og_site_name":"CronDrive Bike-Taxi.it NCC Bruneck Brunico","article_modified_time":"2023-06-14T19:47:41+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"15 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/fahrradtransport.it\/it\/impressum\/","url":"https:\/\/fahrradtransport.it\/it\/impressum\/","name":"Impressum - CronDrive Bike-Taxi.it NCC Bruneck Brunico","isPartOf":{"@id":"https:\/\/fahrradtransport.it\/it\/#website"},"datePublished":"2022-12-08T16:58:41+00:00","dateModified":"2023-06-14T19:47:41+00:00","breadcrumb":{"@id":"https:\/\/fahrradtransport.it\/it\/impressum\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/fahrradtransport.it\/it\/impressum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/fahrradtransport.it\/it\/impressum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/fahrradtransport.it\/it\/home\/"},{"@type":"ListItem","position":2,"name":"Impressum"}]},{"@type":"WebSite","@id":"https:\/\/fahrradtransport.it\/it\/#website","url":"https:\/\/fahrradtransport.it\/it\/","name":"CronDrive Bike-Taxi.it NCC Bruneck Brunico","description":"Biketransport Taxiservice N.C.C.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/fahrradtransport.it\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 14:58:52","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"translation_priority","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/pages\/1284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/comments?post=1284"}],"version-history":[{"count":1,"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/pages\/1284\/revisions"}],"predecessor-version":[{"id":1285,"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/pages\/1284\/revisions\/1285"}],"wp:attachment":[{"href":"https:\/\/fahrradtransport.it\/it\/wp-json\/wp\/v2\/media?parent=1284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}